{"id":101113,"date":"2018-11-18T17:31:12","date_gmt":"2018-11-18T16:31:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/legittimamente-per-migliorare-la-vita-sociale\/"},"modified":"2023-01-16T19:02:27","modified_gmt":"2023-01-16T18:02:27","slug":"264703-legittimamente-per-migliorare-la-vita-sociale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/264703-legittimamente-per-migliorare-la-vita-sociale\/","title":{"rendered":"&#8220;LegittimaMente&#8221; per migliorare la vita sociale"},"content":{"rendered":"<h4>Nasce a Cosenza l\u2019associazione LegittimaMente, organizzazione senza scopo di lucro composta di persone provenienti da diversi settori della societ\u00e0 civile e dei quali sono, a vario titolo, rappresentanti<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L\u2019organizzazione prende forma grazie a un intenso portato conoscitivo messo a disposizione da ciascuno dei singoli associati, con un obiettivo senz\u2019altro ambizioso, messo a fuoco dall\u2019unione di pi\u00f9 visuali convergenti nella comprensione delle cause e degli effetti dello stato in cui attualmente versano le nostre comunit\u00e0.<\/p>\n<p>Mossi dall\u2019imperativo morale di incidere in maniera attiva e positiva il nucleo dell\u2019organizzazione strutturale della vita pubblica e amministrativa, il loro comune fine \u00e8 di contribuire a migliorare la vita sociale, culturale e politica dei nostri territori, a partire dalla citt\u00e0 di Cosenza. A tale scopo, l\u2019associazione LegittimaMente si propone di collaborare con chiunque abbia idea concreta dell\u2019importanza della legittimit\u00e0 dei comportamenti pubblici, della loro etica e del loro pi\u00f9 radicale profilo di legalit\u00e0. L\u2019associazione, perci\u00f2, interagir\u00e0 con ogni risorsa umana disponibile sul territorio d\u2019interesse, con l\u2019anelito di favorire il miglioramento dei livelli culturali, economici, formativi, occupazionali, dell\u2019impresa e della comunicazione.<\/p>\n<p>Presiede l\u2019associazione Katya Gentile, sostenuta e affiancata dal primo direttivo composto da Antonio Anzani Ciliberti, Serafino Tangari, Pietro Francesco Spadafora, Sergio Aquino, Ginette Marra, Luigi Guido. Il Direttivo formalizzer\u00e0 nelle prossime ore le altre cariche interne. \u00abLa &#8220;biodiversit\u00e0&#8221; dei singoli \u2013 dichiara Katya Gentile &#8211; ci rende unici insieme. Il nome che abbiamo scelto, &#8220;LegittimaMente&#8221;, \u00e8 la premessa essenziale, l&#8217;assunto imprescindibile che ci ha unito e da cui partir\u00e0 ogni azione\u00bb. \u00abLa consapevolezza \u2013 continua \u2013 dello svilimento dei principi e dei valori, dei tempi e dei luoghi in cui viviamo, ci spinge alla ricerca di chi, come noi, \u00e8 animato da un fuoco interiore che non lo fa rassegnare a questo status quo e sente, invece, di dover\/voler contribuire in qualche modo al miglioramento della nostra societ\u00e0\u00bb.<\/p>\n<p>\u00abAuspico, quindi \u2013 conclude -, che quello compiuto sia il primo passo verso l&#8217;aggregazione di tutti coloro che si rivedono in tali affermazioni, cos\u00ec come abbiamo fatto noi, senza pregiudizi di sorta. Ringrazio i membri del Consiglio Direttivo che hanno voluto onorarmi della loro fiducia e spero di riuscire a rappresentare al meglio l&#8217;Associazione, assicurando il massimo impegno\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nasce a Cosenza l\u2019associazione LegittimaMente, organizzazione senza scopo di lucro composta di persone provenienti da diversi settori della societ\u00e0 civile e dei quali sono, a vario titolo, rappresentanti<\/p>\n","protected":false},"author":21,"featured_media":101114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-101113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101113"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101114"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}