{"id":101175,"date":"2018-11-20T10:28:06","date_gmt":"2018-11-20T09:28:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/eccellenze-calabresi-premiato-lallenatore-del-rende-modesto\/"},"modified":"2023-01-16T19:02:32","modified_gmt":"2023-01-16T18:02:32","slug":"264924-eccellenze-calabresi-premiato-lallenatore-del-rende-modesto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/264924-eccellenze-calabresi-premiato-lallenatore-del-rende-modesto\/","title":{"rendered":"Eccellenze calabresi, premiato l&#8217;allenatore del Rende Modesto"},"content":{"rendered":"<h4>Impegnato per portare la squadra verso un altro successo Francesco Modesto ha ritirato il premio ieri sottolineando da allenatore oggi, da ex calciatore e soprattutto da calabrese l&#8217;orgoglio di far conoscere la terra calabra attraverso lo sport<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PIANE CRATI (CS) &#8211; Si \u00e8 svolta un\u2019appendice della premiazione delle \u201cEccellenze Calabresi\u201d presso la Sala Ricevimenti \u201cOrchidea Blu\u201d di Piane Crati, dove \u00e8 stato consegnato il riconoscimento, in ambito sportivo, all\u2019allenatore del Rende Calcio 1968, Francesco Modesto assente alla serata di Gala l&#8217;8 ottobre scorso perch\u00e8 impegnato nella partita di rifinitura serale della squadra che nei giorni successivi avrebbe affrontato una difficile gara. L\u2019evento ha visto la partecipazione del Consigliere Regionale Franco Sergio e del Sindaco di Piane Crati, Michele Ambrogio, che hanno consegnato il premio a Francesco Modesto, elogiandone le doti di giocatore prima e di allenatore poi.<\/p>\n<p>Sergio e Ambrogio hanno evidenziato il momento magico che vive il Rende Calcio con la guida attuale augurando un prosieguo di campionato sempre ai massimi livelli. Ha preso, infine, la parola un emozionato Modesto, di nome e di fatto, che ha esaltato le doti e l\u2019impegno dei \u201csuoi ragazzi\u201d. Modesto che per\u00a0 la sua giovane et\u00e0, pi\u00f9 vicina a quella da calciatore che non da allenatore, ha dimostrato e continua a dimostrare un&#8217;alta professionalit\u00e0 e responsabilit\u00e0 sul campo e tra i calciatori, proprio nella sua nuova veste, raccogliendo grandi consensi da tutto il mondo calcistico e non. Nel suo breve discorso di ringraziamento Modesto ha vantato una squadra che rispecchia le origini calabre: la maggior parte dei giocatori, infatti, sono di Cosenza e provincia per cui, essendo lui originario di Crotone, ancor di pi\u00f9 oggi si pu\u00f2 parlare di valore aggiunto in una regione solitamente conosciuta sui giornali e media in generale, per fatti quasi sempre negativi.<\/p>\n<p>Modesto, concludendo, ha dichiarato di essere orgoglioso &#8220;di riuscire a far parlare i media nazionali della Citt\u00e0 di Rende e della Calabria&#8221;. L\u2019evento si \u00e8 concluso fra abbracci e strette di mano alla presenza di numerosi tifosi e affezionati dello sport. Presenti alla cerimonia di premiazione anche il presidente Angelo Cosentino e il responsabile cerimoniale stampa\u00a0Pasquale Giardino dell&#8217;Ancri, Associazione cavalieri al merito della Repubblica<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-264952 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/43d9bcd7-f6b6-463a-8f63-33351d9698c4-440x214.jpg\" alt=\"\" width=\"440\" height=\"214\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-264958 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/5a7dbb32-82d2-4a59-a0ed-26e620308954-440x214.jpg\" alt=\"\" width=\"440\" height=\"214\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impegnato per portare la squadra verso un altro successo Francesco Modesto ha ritirato il premio ieri sottolineando da allenatore oggi, da ex calciatore e soprattutto da calabrese l&#8217;orgoglio di far conoscere la terra calabra attraverso lo sport<\/p>\n","protected":false},"author":37,"featured_media":101176,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,44,20],"tags":[],"class_list":["post-101175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-rende","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101175"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101176"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}