{"id":101247,"date":"2018-11-21T14:30:28","date_gmt":"2018-11-21T13:30:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sorrisi-e-note-torna-di-scena-la-terra-di-piero-e-la-solidarieta-video-e-foto\/"},"modified":"2023-01-16T19:02:37","modified_gmt":"2023-01-16T18:02:37","slug":"265207-sorrisi-e-note-torna-di-scena-la-terra-di-piero-e-la-solidarieta-video-e-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/265207-sorrisi-e-note-torna-di-scena-la-terra-di-piero-e-la-solidarieta-video-e-foto\/","title":{"rendered":"&#8220;Sorrisi e note&#8221;, torna di scena la Terra di Piero e la solidariet\u00e0 (video e foto)"},"content":{"rendered":"<h4>Venerd\u00ec 7 dicembre, alle ore 20.30, presso il cine teatro Garden di Rende andr\u00e0 in scena &#8220;Sorrisi e note&#8221;, una serata a sostegno del progetto Saam in Namibia con Checco Pallone, Simona Micieli, Dario Brunori, Peppe Voltarelli, Sas\u00e0 Calabrese, Antonio Filippelli, Eliseno Sposato e Roberto Giacomantonio in &#8220;Tre uomini e na seggia&#8221;<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-266735 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/37b55bbd-711d-47d4-b51a-9815da901e17-179x280.jpg\" alt=\"\" width=\"179\" height=\"280\" title=\"\">COSENZA &#8211; Ci risiamo, Sergio Crocco e la Terra di Piero ancora una volta tirano fuori dal cappello magico un&#8217;altra chicca per Cosenza, &#8220;Sorrisi e note&#8221;, l&#8217;evento che apre le festivit\u00e0 natalizie nella citt\u00e0 bruzia; il vero evento potremmo definirlo, degno di aprire il Natale cosentino perch\u00e8 creato per portare solidariet\u00e0, aiuti, pace, amore e sorrisi. L&#8217;intento dell&#8217;evento, come tutti quelli realizzati dall&#8217;<strong>associazione del &#8220;fare&#8221; e non del dire<\/strong> \u00e8 quello di raccogliere fondi per il nuovo progetto che migliorer\u00e0 la vita ai tanti bambini della Namibia, che ci piace sempre sottolineare, un&#8217;altra figlia di mamma Africa. Perch\u00e8 Sergio Crocco ci mette la faccia, tutti gli associati della Terra di Piero ci mettono la faccia, il tempo, il denaro e soprattutto ci credono. Ed infatti le opere si realizzano, gli aiuti arrivano e qualche sorriso in pi\u00f9, su questa terra, si riesce a regalare a piccoli innocenti che non hanno colpe; bambini che non hanno il tempo di fare i capricci &#8211; come racconta Sergio Crocco &#8211;\u00a0 perch\u00e8 non conoscono il significato della parola capriccio, perch\u00e8 devono cercare di sopravvivere alla povert\u00e0 ed alla fame.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_265216\" style=\"width: 313px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-265216\" class=\"wp-image-265216\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45548048_10218040997678807_1702552154557906944_n-210x280.jpg\" alt=\"\" width=\"303\" height=\"404\" title=\"\"><p id=\"caption-attachment-265216\" class=\"wp-caption-text\">Baraccopoli infinita di Goreangab, Windhoek, Namibia. Nella maggior parte delle lingue africane \u00e8 inesistente la parola &#8220;capriccio&#8221;. Lui non avrebbe tempo ne forza per farne. Questo bimbo ritorna con l&#8217;acqua da portare nella sua capanna. Questo bimbo dovrebbe solo giocare.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Sorrisi e Note, 7 dicembre<\/strong>, nel giorno della <strong>vigilia dell&#8217;Immacolata<\/strong>\u00a0per accogliere tra musica, spettacolo, teatro, risate e cuddruriaddri tutti coloro che vorranno donare un sorriso ad un bimbo, alla modica cifra di 10 euro, un biglietto acquistabile presso la Terra di Piero oppure &#8220;In Prima Fila&#8221;. Lo spettacolo a sostegno del progetto Saam in Namibia, che significa &#8220;Insieme&#8221;, vedr\u00e0 la presenza di grandi nomi :\u00a0<strong>Checco Pallone, Simona Micieli, Dario Brunori, Peppe Voltarelli, Sas\u00e0 Calabrese, e il trio che sta spopolando Antonio Filippelli, Eliseno Sposato e Roberto Giacomantonio in &#8220;Tre uomini e na seggia&#8221;<\/strong><\/p>\n<p>A conti fatti sarebbero due pacchetti di sigarette in meno, una pizza ed una birra in meno, un giro in macchina in meno&#8230;piccole privazioni che contribuirebbero a realizzare il grande container che per marzo prossimo partir\u00e0 per la Namibia. <strong>Il terzo container che la Terra di Piero realizza e porta a destinazione: Madagascar, Tanzania e oggi Namibia<\/strong>. Dal primo dicembre partir\u00e0 la raccolta di beni di prima necessit\u00e0 da portare ai bambini in Africa. E insieme al container ci sar\u00e0 bisogno di tanto altro. Per questo che la Terra di Piero, come sempre si appella a tutta la solidariet\u00e0 dei cosentini e di tutti coloro che hanno conosciuto il lavoro svolto dall&#8217;associazione e soprattutto le opere portate a termine.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-265230 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/46482014_10218105956222730_5903914864589406208_n-440x220.jpg\" alt=\"\" width=\"514\" height=\"257\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2>NAMIBIA, DIARIO DI BORDO DI SERGIO CROCCO<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-265231 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45487215_10218031511721664_8847123362602811392_n-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\">Crocco insieme al altre sette compagni di viaggio a fine ottobre \u00e8 partito per una ricognizione e lui stesso racconta di avere conosciuto un&#8217;altra Africa, con ancora tanta troppa sofferenza. La gente, i bambini, vivono in baraccopoli di lamiera dove resistere al caldo &#8220;rovente&#8221;, che ti cucina la pelle, \u00e8 da eroi. &#8220;<em>Ai nostri occhi si materializza la baraccopoli di Goreangab nel quartiere di Katutura che\u00a0in lingua Herero vuol dire \u201cposto dove nessuno vuole stare\u201d. Qui la sopravvivenza \u00e8 il problema principale e quotidiano<\/em> &#8211; racconta Crocco nel suo diario di bordo -.\u00a0<em>Ci spostiamo di baraccopoli e andiamo a Soweto, non prima d\u2019avere verificato la razionalizzazione dell\u2019acqua in tutte le baraccopoli namibiane. Un problema che diventa anche di salute pubblica<\/em>&#8220;. Il racconto di Crocco\u00a0 porta alla luce delle terribili realt\u00e0: &#8220;<em>Altro giro nell\u2019ennesima baraccopoli di Ochomuse, dove l\u2019asilo Clever Kids cura e cresce 24 bambini di una zona altrettanto malfamata.\u00a0<\/em><br \/>\n<em>Altro spostamento all\u2019interno di Katutura e ci troviamo all\u2019orfanorofio Orlindi. Bambini che ti guardano, ti prendono la mano e non te la lasciano pi\u00f9, esattamente come in Tanzania. E rivedo gli occhi di creature di pochi anni disperate e serene. Contraddizioni d\u2019Africa. Terminiamo il giro dei due giorni a Windhoek nel Centro Khomasdal, gestito da una donna tedesca di nome e di fatto. Anita cura con amorevole fermezza 160 bambini disabili, soprattutto mentali. Un ambiente pulitissimo ed organizzato dove tanti bimbi e ragazzi con disabilit\u00e0 anche gravissime hanno una possibilit\u00e0, semplicemente una possibilit\u00e0. Abbiamo \u201cattenzionato\u201d questo posto come possibile zona dove costruire il Parco Piero Romeo tre<\/em>&#8220;.<\/p>\n<h2><\/h2>\n<h2>IL SORRISO DI GRACE E DI TUTTI I BIMBI DI MAMMA AFRICA &#8220;NON ESISTE RICCHEZZA PIU&#8217; GRANDE&#8221;<\/h2>\n<p>Ad oggi, parlando con tutti coloro che hanno messo piede in Africa, insieme alla Terra di Piero, non si \u00e8 ancora sentita una sola persona che abbia detto &#8220;sono solo chiacchiere&#8221; e mai nessuno potr\u00e0 dirlo. E non parliamo del &#8220;popolino&#8221;, se qualcuno avesse avuto il minimo pensiero che in questi viaggi trovino posto solo chi &#8220;non ha niente di meglio da fare&#8221;. Nei viaggi della Terra di Piero in Africa, a portare aiuti fattivi sono partiti per &#8220;sporcarsi le mani di amore&#8221; e senza riflettori accesi, imprenditori, politici, giovani, artisti, insegnanti, professionisti&#8230;.e tutti al rientro sono diventati pi\u00f9 ricchi, proprio come suol dire sempre Sergio Crocco &#8220;<em><strong>Il mio \u00e8 un guadagno pi\u00f9 \u201calto\u201d, non numerabile, incommensurabile.<\/strong>\u00a0<strong>Bambini che hanno visto la loro qualit\u00e0 della vita migliorata, anche se di poco perch\u00e9 \u00e8 poco ci\u00f2 che noi possiamo riuscire a fare,<\/strong> <strong>mi fanno arricchire in modo esponenziale<\/strong><\/em>&#8220;.<\/p>\n<p>A dare benzina a questa opera coraggiosa della Terra di Piero sono i sorrisi dei bambini; sorrisi innocenti e la speranza di una vita migliore. E da Cosenza, da una citt\u00e0 del sud, dal &#8220;piede&#8221; dell&#8217;Italia c&#8217;\u00e8 un gruppo di &#8220;folli&#8221; dell&#8217;amore per il prossimo che, sostenuti dal grande cuore e dalla solidariet\u00e0 dei cosentini, ci sta provando e ad oggi \u00e8 riuscito a lasciare un segno tangibile, proprio per quei sorrisi di innocenti che hanno diritto a vivere una vita dignitosa. Racconta sempre Crocco nel suo diario di bordo:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-265212 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45144580_10217990251410182_6564726940635234304_n-210x280.jpg\" alt=\"\" width=\"250\" height=\"333\" title=\"\">&#8220;I<em>n questa foto trovate il volto di Grace, Ha tre anni, vive nella grande baraccopoli di Mondesa, alla periferia di Swakopmund, citt\u00e0 affacciata sul mare\u00a0<\/em><em>atlantico. Grace l\u2019abbiamo incontrata nell\u2019Asilo costruito dai ragazzi di Mammad\u00f9 Onlus Italia proprio nel centro della baraccopoli.\u00a0<\/em><em>Le baracche in cui ci entri e te ne esci subito perch\u00e9 il caldo ti massacra, e ti scervelli pensando a come faccia Grace a vivere in quelle condizioni, come sia possibile che ci stia passando la sua infanzia. Eppure Grace ci sorride e ci sfotte. Lo fa con una naturalezza che ti disarma, che vorresti prendertela e portarla in Italia e andare a comprarle 1000 giocattoli, darle la frescura di un ventilatore, farle provare l\u2019ebbrezza di un cono da Zorro che le possa \u2018nzivare il mento. Insomma, darle un futuro. Invece non puoi e, forse, \u00e8 meglio cos\u00ec. Non sapr\u00f2 mai se il sorriso di Grace resterebbe intatto di fronte alle comodit\u00e0 europee. So di certo che meriterebbe una vita un poco pi\u00f9 dignitosa. Meriterebbe di non viverla a Mondesa, baraccopoli creata dopo la finta caduta dell\u2019Apartheid per dimostrare al popolo che si poteva stare peggio. Una vita dignitosa, dicevo. Quella che vorrebbero vivere i bambini di Oshakati, Oshikuku e tutta la fascia a nord del Parco Nazionale dell\u2019Etosha&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>L&#8217;EVENTO DELLA SOLIDARIETA&#8217; A CUI NON SI PUO&#8217; MANCARE<\/h2>\n<p>&#8220;Sorrisi e note&#8221;, dunque, per portare gioia. Partecipare per dire &#8220;c&#8217;ero anche io&#8221;, perch\u00e8 nel guardare la foto di Grace ognuno possa dire &#8220;ho contribuito anche io a far sorridere i bambini&#8221;. E se gli artisti si prestano con cuore alla realizzazione di un evento con uno scopo nobile, la citt\u00e0 di Cosenza deve continuare a rispondere con lo stesso spirito nobile, come ha fatto da sempre, sin dall&#8217;inizio della nascita dell&#8217;associazione nel lontano 2011 perch\u00e8 come diceva <strong>Piero Romeo &#8220;<em>Sono quelle cose che alla fine ti rimangono<\/em>&#8220;<\/strong><\/p>\n<p>Nel suo diario di bordo Crocco termina questo viaggio di ricognizione con la promessa di ritornare per portare aiuti: &#8220;<em>La Namibia. Stupenda ed atroce. Divina nelle bellezze naturali (da togliere il fiato) e odiosa nelle discriminazioni sociali e di classe. <strong>La Namibia per me \u00e8 per\u00f2 il sorriso di Grace. Io riparto da lei<\/strong>. Riempiremo un container intero che possa ripagare il suo sorriso ed i suoi scherzi. Il paliatone che mi ha fatto e la girandola di emozioni che ha regalato a tutti noi questa figlia di \u2018ntrocchia malefica e travolgente, non rester\u00e0 \u201cimpunito\u201d. Lo faremo c<strong>ercando di migliorare la qualit\u00e0 della vita delle tante Grace che popolano la Namibia.\u00a0<\/strong>\u00a0<strong>E\u2019 il vero prossimo obiettivo della Terra di Piero nei mesi che verranno. Ce la faremo. Ripartiremo a met\u00e0 Aprile. Per Grace e per un sorriso che travolge.<\/strong><\/em><\/p>\n<p><em>Sergio Crocco&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\">PROMO &#8220;SORRISI E NOTE&#8221;<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"&quot;Sorrisi e note&quot;\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/c7YX0bcn6i4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff0000;\">L&#8217;AFRICA DELLA TERRA DI PIERO<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265232\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31171539_10216502695822222_4055511199821856768_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265233\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31369592_10216444679691855_4349502449967431680_n-440x175.jpg\" alt=\"\" width=\"440\" height=\"175\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265234\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31599828_10216503967334009_8488718842946650112_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265235\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31749669_10216502696422237_8119149426955517952_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265236\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31870437_10216493858001282_5057292156742402048_n-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265237\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31882993_10216503962373885_8937133511916126208_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265238\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31902162_10216503967894023_8255730744177983488_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265239\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/31949995_10216503960413836_8953232470975709184_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265240\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/32073155_10216540985339436_8983380658902532096_n-181x280.jpg\" alt=\"\" width=\"181\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265241\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/33767891_10216688450305968_5025217328090972160_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265242\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/33964679_10216697389769449_1239318723135799296_n-158x280.jpg\" alt=\"\" width=\"158\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265243\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36225884_10216935252355865_960227758217101312_n-187x280.jpg\" alt=\"\" width=\"187\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265244\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36385976_10216958358293499_5073283002885210112_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265245\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36394076_10216957871441328_7360818091229446144_n-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265246\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36521821_10216964888536751_4999253958728876032_n-277x280.jpg\" alt=\"\" width=\"277\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265247\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36623651_10216987966793693_3888130208263307264_n-280x280.jpg\" alt=\"\" width=\"280\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265248\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/36722361_10216988184199128_7052426764928155648_n-158x280.jpg\" alt=\"\" width=\"158\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265249\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/41215775_10217549235225053_3948173284125704192_n-276x280.jpg\" alt=\"\" width=\"276\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265250\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45144580_10217990251410182_6564726940635234304_n-1-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265251\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45159253_10217990250690164_461514048639336448_n-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265252\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45213292_10217984667590590_3261880550092177408_n-196x280.jpg\" alt=\"\" width=\"196\" height=\"280\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265377\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/20160914155161957100-420x280.jpg\" alt=\"\" width=\"420\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265253\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45423999_10218016158097833_3775067376039493632_n-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265254\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45487215_10218031511721664_8847123362602811392_n-1-210x280.jpg\" alt=\"\" width=\"210\" height=\"280\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-265255\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/45677032_10218028685931021_2936567903048171520_n-213x280.jpg\" alt=\"\" width=\"213\" height=\"280\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 7 dicembre, alle ore 20.30, presso il cine teatro Garden di Rende andr\u00e0 in scena &#8220;Sorrisi e note&#8221;, una serata a sostegno del progetto Saam in Namibia con Checco Pallone, Simona Micieli, Dario Brunori, Peppe Voltarelli, Sas\u00e0 Calabrese, Antonio Filippelli, Eliseno Sposato e Roberto Giacomantonio in &#8220;Tre uomini e na seggia&#8221;<\/p>\n","protected":false},"author":40,"featured_media":101248,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,40],"tags":[],"class_list":["post-101247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101247"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101248"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}