{"id":101606,"date":"2018-11-30T06:30:27","date_gmt":"2018-11-30T05:30:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aldo-mazzei-presenta-lequilibrista-con-la-direzione-artistica-di-grazia-di-michele\/"},"modified":"2023-01-16T19:03:01","modified_gmt":"2023-01-16T18:03:01","slug":"266699-aldo-mazzei-presenta-lequilibrista-con-la-direzione-artistica-di-grazia-di-michele","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/266699-aldo-mazzei-presenta-lequilibrista-con-la-direzione-artistica-di-grazia-di-michele\/","title":{"rendered":"Aldo Mazzei, presenta &#8216;L&#8217;Equilibrista&#8217; con la direzione artistica di Grazia Di Michele"},"content":{"rendered":"<p><strong>Da oggi on line e disponibile su tutte le piattaforme di vendita &#8216;L\u2019equilibrista&#8217; di Aldo Mazzei, giovane cantante originario di Cosenza.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u201c<em>Abbiamo girato tra Bari e Polignano<\/em>\u00a0\u2013 ha spiegato l\u2019artista cosentino \u2013\u00a0<em>scegliendo tre location in particolare. La prima scena \u00e8 girata in una strada, la seconda in un percorso di campagna e la terza su un molo, in modo da mettere in evidenza lo splendido mare della citt\u00e0 di Mister Volare, ma anche gli stati d\u2019animo dell\u2019individuo<\/em>\u201d.<\/p>\n<p>Il<strong> testo<\/strong> \u00e8 una metafora su una storia d\u2019amore di un ragazzo e come esso anche la parte video vuole rappresentare questo. Due le figure in scena. Il protagonista \u00e8 un ragazzo che rappresenta l\u2019equilibrista e come seconda comparsa c\u2019\u00e8 una ballerina, che rappresenta la sua compagna, la quale pian piano si allontana dall\u2019inquadratura, mentre il giovane perde l\u2019equilibrio. Questo lavoro \u00e8 stato realizzato dalla Soundmusic con la regia della giovane video maker barese Faby Spaziani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-266706 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/42797567_1874676849247224_8048992742493126656_n-735x312.jpg\" alt=\"\" width=\"735\" height=\"312\" title=\"\"><\/p>\n<p>Il brano di Aldo Mazzei ha la supervisione di <strong>Grazia Di Michele<\/strong>, nota cantante e autrice, ex docente del talent show \u201cAmici\u201d in onda sulle reti Mediaset. La musica, che \u00e8 stata scritta dalla cantautrice di Cosenza <strong>Ida Scarlato<\/strong>, ha delle sonorit\u00e0 tipicamente pop e si rif\u00e0 al cantautorato italiano. \u201cL\u2019equilibrista\u201d \u00e8 stato registrato presso lo studio di registrazione \u201cDelta top Edizioni musicali\u201d di Roma, \u00e8 ha visto collaborare, per l\u2019arrangiamento, anche Andy Bartolucci, Fabrizio Settimi, Marco Valerio Cecilia e Claudio Bartolucci, musicisti e collaboratori della nota artista. \u201c<em>Dopo anni di studio sono finalmente riuscito a partire con un progetto mio, piene di idee e collaboratori, abili professionisti, che mi sostengono. Di sicuro questo brano sar\u00e0 il primo di una lunga serie di lavori e sono molto felice di essere riuscito nel realizzarlo<\/em>\u00a0<em>e spero che Polignano porti fortuna anche a me e mi permetta di volare<\/em>\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-266700 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/11\/Aldo-Mazzei-300x400.jpg\" alt=\"\" width=\"300\" height=\"400\" title=\"\"><\/p>\n<p>Nato nel 1991, Aldo Mazzei ha avuto il suo incontro con la musica a 14 anni in occasione della rivisitazione del musical Notre Dame de Paris, organizzata dalla Provincia di Cosenza, al quale ha partecipato, superando i provini. Successivamente ha studiato con l\u2019associazione musicale Cantica di Settimo di Montalto. Qui ha avuto modo di partecipare a una masterclass diretta da Grazia Di Michele, che dopo averlo notato ha scelto di seguirlo, investendo su di lui.<\/p>\n<p><b>Aldo sar\u00e0 in diretta stamattina, alle 12.30, su Rlb per presentare &#8216;<strong>L\u2019equilibrista&#8217;.<\/strong><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da oggi on line e disponibile su tutte le piattaforme di vendita &#8216;L\u2019equilibrista&#8217; di Aldo Mazzei, giovane cantante originario di Cosenza.<\/p>\n","protected":false},"author":20,"featured_media":101607,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40,1],"tags":[],"class_list":["post-101606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101606"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101607"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}