{"id":10164,"date":"2012-12-21T12:50:19","date_gmt":"2012-12-21T11:50:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=10164"},"modified":"2023-01-17T13:43:19","modified_gmt":"2023-01-17T12:43:19","slug":"4558-legambiente-calabria-serve-sistematicita-di-azioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4558-legambiente-calabria-serve-sistematicita-di-azioni\/","title":{"rendered":"Legambiente Calabria: serve sistematicit\u00e0 di azioni"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; &nbsp;Alla vigilia delle festivita&#8217; natalizie, e&#8217; caos tra Reggio e Catanzaro, invase dalla spazzatura per via della chiusura delle discariche che, fino ad oggi,<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">hanno consentito di rinviare la questione. Un&#8217;emergenza, quella dei rifiuti calabresi, sempre rinviata e mai affrontata con la giusta attenzione e di interazioni istituzionali. Francesco Falcone, presidente di Legambiente Calabria, parla di &#8220;un tema che va affrontato &#8220;di petto&#8221; ma fuori dalla logica nefasta dell&#8217;emergenza che ha condotto la regione sulla soglia del disastro ambientale. Come dimostrano i &#8220;Comuni Ricicloni&#8221; d&#8217;Italia, la via della differenziata non e&#8217; utopia, ma l&#8217;unica vera strategia vincente in grado di risolvere e anzi trasformare in opportunita&#8217; la questione dei rifiuti&#8221;. A un anno di distanza dalla crisi, altrettanto grave, dell&#8217;autunno 2011 si riapre dunque &#8211; aggiunge &#8211; la questione discariche. Una questione mai seriamente affrontata in Calabria. Pianopoli, Alli (in provincia di Catanzaro) e Casignana (nella Locride) sono ormai al collasso ne&#8217; sono ipotizzabili forzature in territori che, alla luce dei recenti scandali, hanno gia&#8217; pagato un prezzo altissimo in termini di inquinamento ambientale e necessiterebbero piuttosto di una seria bonifica. Mentre a Catanzaro ci si prepara ad affrontare il nuovo anno con i cumuli di rifiuti a fare da coreografia, a Reggio prosegue la crisi della raccolta, in relazione alle difficolta&#8217; dell&#8217;impianto di Sambatello, a cui si aggiungera&#8217; quello di Casignana fino al 31 dicembre. Una soluzione tampone voluta dal Commissario delegato per l&#8217;emergenza rifiuti in Calabria proprio per accelerare il ritorno alla &#8220;normalita&#8217;&#8221; in riva allo Stretto. E&#8217; chiaro &#8211; conclude &#8211; che il servizio di raccolta subisce un brusco rallentamento, azzerando i progressi registrati nelle ultime settimane&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; &nbsp;Alla vigilia delle festivita&#8217; natalizie, e&#8217; caos tra Reggio e Catanzaro, invase dalla spazzatura per via della chiusura delle discariche che, fino ad oggi,<\/p>\n","protected":false},"author":22,"featured_media":10165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-10164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=10164"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/10165"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=10164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=10164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=10164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}