{"id":101665,"date":"2018-12-02T09:00:36","date_gmt":"2018-12-02T08:00:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lettura-consigliata-ad-un-pubblico-abbastanza-adulto\/"},"modified":"2023-01-16T19:03:05","modified_gmt":"2023-01-16T18:03:05","slug":"266911-lettura-consigliata-ad-un-pubblico-abbastanza-adulto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/266911-lettura-consigliata-ad-un-pubblico-abbastanza-adulto\/","title":{"rendered":"Lettura consigliata ad un pubblico (abbastanza) adulto"},"content":{"rendered":"<h4>Quando raggiungiamo la vecchiaia il desiderio pi\u00f9 grande, per la maggior parte di noi, \u00e8 quello di poter tornare indietro a quando eravamo giovani. Ma siamo sicuri che ci\u00f2 ci porterebbe qualche vantaggio?<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>E\u2019 evidente che il motivo che maggiormente ci porta a desiderare di ritornare giovani sia la paura della morte, e la cosa \u00e8 del tutto <strong>comprensibile<\/strong>, ma questo non pu\u00f2 giustificare, se riflettiamo bene, il nostro desiderio di iniziare da capo una nuova vita. Eppure, quando eravamo abbastanza adulti, ma non ancora vecchi, la vecchiaia rappresentava il nostro traguardo e per raggiungerla alcuni di noi erano <strong>capaci di privarsi anche di molti piaceri<\/strong>. Durante il passaggio delle varie fasi della vita che conduce alla vecchiaia sono diverse le nostre considerazioni nei suoi confronti.<\/p>\n<p><strong>Da fanciulli e da giovanissimi,<\/strong> pur sentendone parlare, la associamo alla fine della vita ma ciononostante ci comportiamo come se essa non esistesse. La nostra vita \u00e8 improntata al \u201c<strong>qui ed ora<\/strong>\u201d, e la temerariet\u00e0 non \u00e8 una sfida alla morte, ma \u00e8 dovuta solo alla inconsapevolezza del valore della vita. In tale prospettiva, c\u2019\u00e8 da parte nostra una scarsa considerazione della vecchiaia o, forse pi\u00f9 precisamente, la vediamo come qualcosa che non ci riguarda. E se per caso dovessimo venire a contatto con qualche rappresentante di tale \u201c<strong>stagione della vita<\/strong>\u201d, spesso diventiamo insofferenti, perch\u00e9 pensiamo che da quell\u2019incontro trarremo solo delle scocciature. Quando, ad esempio, <strong>incrociamo per strada una persona anziana,<\/strong> abbiamo l\u2019impressione che essa possa intralciare la nostra corsa affannosa verso qualcosa, spesso di neanche ben definito. E la smania di fare o di possedere questo qualcosa ci porta a non considerare quelle che sono <strong>le sue esigenze, le sue difficolt\u00e0.<\/strong><\/p>\n<p>Una volta diventati pi\u00f9 adulti pensiamo alla vecchiaia, ma la vediamo ancora molto distante e, a volte, ce ne facciamo un\u2019idea romantica. Pensiamo che essa rappresenti il raggiungimento ed il riconoscimento di una certa <strong>saggezza<\/strong> ( cose che non sempre si verificano ), e ci\u00f2 ci tranquillizza e ci d\u00e0 la sensazione che raggiungerla alla fine potr\u00e0 portarci dei vantaggi.<\/p>\n<p>E\u2019 soltanto in et\u00e0 a avanzata, quando siamo sulla sua soglia, che essa inizia a riempire i nostri pensieri, ed \u00e8 allora che incomincia ad esercitare su di noi una certa seduzione l\u2019idea che sarebbe bello poter tornare indietro, al tempo in cui eravamo ragazzi. Questo desiderio, per\u00f2, al di l\u00e0 della sua evidente impraticabilit\u00e0, anche qualora potesse essere esaudito, non apporterebbe, a mio avviso, nessun vantaggio. Si tratterebbe di vivere una vita che non sarebbe la continuazione della nostra vita, magari aggiornata, e con la possibilit\u00e0 di poterne conservare e mantenere una certa consapevolezza, una memoria capace di preservarci dal commettere gli stessi errori che abbiamo compiuto nella vita in corso. <strong>Sarebbe una vita tutta nuova<\/strong>.<\/p>\n<p>Ben diverso sarebbe se questo tornare indietro negli anni fosse come avere una seconda possibilit\u00e0, per recuperare rapporti che non hanno avuto l\u2019evoluzione che speravamo, magari anche per colpa nostra. Nel caso di un ritorno indietro conservando la consapevolezza (la coscienza) della vita passata e con la possibilit\u00e0 di ritrovare intorno a noi gli stessi visi di allora, questo s\u00ec che avrebbe senso. Eccome! Ci\u00f2 ci consentirebbe di vivere in maniera diversa, o solo pi\u00f9 intensamente, quei rapporti,alcuni dei quali rimasti magari irrisolti.<\/p>\n<p>Al di fuori di questa modalit\u00e0, invece, tornare indietro con l\u2019et\u00e0 equivarrebbe a voler nascere un\u2019altra volta , e i benefici e i vantaggi potrebbero non esserci. Si tratterebbe di una vita completamente nuova, che vivremmo come una vita normale, come una cosa scontata. Ci <strong>sarebbero nuove possibilit\u00e0, nuove potenzialit\u00e0 ed un\u2019evoluzione imprevedibile,<\/strong> non necessariamente assimilabile a quella precedente. E la vecchiaia, tra l\u2019altro, a differenza della vita passata, dove essa era stata raggiunta, in questa nuova vita potrebbe anche non esserci garantita. La nostra esistenza terrena, infatti, potrebbe concludersi prima di raggiungere quella fase della vita, impedendoci di veder realizzati alcuni dei nostri progetti o di poter assistere a determinati eventi. Cose che in definitiva rappresentano il modo per concludere il nostro passaggio sulla terra, non dico con distacco, ma quantomeno con un po\u2019 di soddisfazione e quindi di serenit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando raggiungiamo la vecchiaia il desiderio pi\u00f9 grande, per la maggior parte di noi, \u00e8 quello di poter tornare indietro a quando eravamo giovani. Ma siamo sicuri che ci\u00f2 ci porterebbe qualche vantaggio?<\/p>\n","protected":false},"author":31,"featured_media":101666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-101665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101665"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101666"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}