{"id":101686,"date":"2018-12-01T06:53:35","date_gmt":"2018-12-01T05:53:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/centrale-biomasse-del-mercure-respinto-ricorso-del-forum-ambientalista-s-gioia\/"},"modified":"2023-01-16T19:03:07","modified_gmt":"2023-01-16T18:03:07","slug":"266987-centrale-biomasse-del-mercure-respinto-ricorso-del-forum-ambientalista-s-gioia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/266987-centrale-biomasse-del-mercure-respinto-ricorso-del-forum-ambientalista-s-gioia\/","title":{"rendered":"Centrale biomasse del Mercure, respinto ricorso del Forum Ambientalista &#8220;S. Gioia&#8221;"},"content":{"rendered":"<h4>La quarta sezione del Consiglio di Stato ha respinto il ricorso presentato dal Forum ambientalista &#8220;Stefano Gioia&#8221; contro la terza autorizzazione concessa dalla Regione Calabria alla Centrale a biomasse della Valle del Mercure<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Il pronunciamento del massimo organismo della giustizia amministrativa \u00e8 arrivato sei mesi dopo l&#8217;udienza di merito. &#8220;Un brutto giorno &#8211; \u00e8 detto in una nota del Forum ambientalista &#8211; per chi crede che legalit\u00e0 e giustizia debbano camminare insieme. <strong>Oggi hanno vinto interessi speculativi e predatori<\/strong> che hanno aggredito un territorio unico, quello del<strong> Parco Nazionale del Pollino, Zona di protezione speciale<\/strong> (Zps) e <strong>Patrimonio dell&#8217;Umanit\u00e0 dell&#8217;Unesco,<\/strong> impattando con tutta la forza delle loro 350 mila tonnellate di alberi mandati in fumo ogni anno e con quella dei cento camion che ogni giorno portano ci\u00f2 che resta di quegli alberi nella pancia del <strong>&#8216;Mostro del Mercure<\/strong>&#8216;. Esponendo, inoltre, le popolazioni residenti a rischi per la salute e a rischi sociali, oltre che ai danni occupazionali negli ambiti propri di un Parco: il turismo e la produzione agro-alimentare di qualit\u00e0. Il tutto con la complicit\u00e0 e il supporto dell&#8217;Ente Parco che, con ogni evidenza, lavora alacremente perch\u00e9&amp;hellip non vi sia pi\u00f9 un Parco Nazionale del Pollino&#8221;.<\/p>\n<p>&#8220;Ma la <strong>battaglia del Forum &#8216;Stefano Gioia<\/strong>&#8216; &#8211; \u00e8 detto ancora nel comunicato &#8211; <strong>non si arresta di certo.<\/strong> Sedici anni di vertenza non ci hanno fiaccato, ci hanno reso pi\u00f9 forti. Quello di oggi \u00e8 un incidente di percorso, grave e incomprensibile, ma contingente. Ci sono (tante) altre strade da percorrere e noi le percorreremo tutte per arrivare all&#8217;unica soluzione possibile e accettabile: chiusura e smantellamento della centrale del Mercure&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La quarta sezione del Consiglio di Stato ha respinto il ricorso presentato dal Forum ambientalista &#8220;Stefano Gioia&#8221; contro la terza autorizzazione concessa dalla Regione Calabria alla Centrale a biomasse della Valle del Mercure<\/p>\n","protected":false},"author":22,"featured_media":101687,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-101686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101686"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101687"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}