{"id":101767,"date":"2018-12-03T14:53:59","date_gmt":"2018-12-03T13:53:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/abbandono-rifiuti-vandalismo-abusivismo-cosenza-e-rende-unite-per-il-decoro-urbano\/"},"modified":"2023-01-16T19:03:12","modified_gmt":"2023-01-16T18:03:12","slug":"267329-abbandono-rifiuti-vandalismo-abusivismo-cosenza-e-rende-unite-per-il-decoro-urbano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/267329-abbandono-rifiuti-vandalismo-abusivismo-cosenza-e-rende-unite-per-il-decoro-urbano\/","title":{"rendered":"Abbandono rifiuti, vandalismo, abusivismo: Cosenza e Rende unite per il decoro urbano"},"content":{"rendered":"<h4>Verso il Piano del Decoro Urbano unico. Tra le tante proposte emerse l&#8217;organizzazione tra Rende e Cosenza di\u00a0<strong>maratone di educazione civica, coinvolgendo i cittadini, con tanto di sacchetti, pinze e guanti, nella pulizia di pezzi di citt\u00e0, dove si annida maggiormente il degrado<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; C&#8217;\u00e8 piena convergenza tra i Presidenti delle commissioni consiliari ambiente dei Comuni di Cosenza e Rende, Vincenzo Granata e Marco Greco, sulla necessit\u00e0 di pervenire prima possibile alla elaborazione di un Piano del Decoro Urbano che possa disciplinare e regolamentare una materia alquanto delicata ed importante per la vita della comunit\u00e0 amministrata. Il comune obiettivo \u00e8 stato messo a fuoco questa mattina a Palazzo dei Bruzi nel corso della seduta della Commissione consiliare ambiente, presieduta dal consigliere Vincenzo Granata, cui \u00e8 stato invitato l&#8217;omologo del Comune di Rende Marco Greco. \u201c<strong>Attualmente sia a Cosenza che a Rende \u2013 ha sottolineato nella sua introduzione Vincenzo Granata \u2013 non esiste un piano del Decoro Urbano appropriato.<\/strong> L&#8217;art.12 comma 3 del Regolamento comunale \u2013 ha detto ancora Granata \u2013 riconosce alle commissioni consiliari la possibilit\u00e0 di assumere iniziative o formulare proposte da sottoporre poi all&#8217;attenzione del Sindaco.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>E la proposta che sia Granata che il Presidente della commissione ambiente rendese Greco intendono portare all&#8217;attenzione dei rispettivi sindaci, ma anche degli assessori al ramo (nel caso di Cosenza a Carmine Vizza) e dei Presidenti del Consiglio comunale, \u00e8 proprio quella di elaborare un Piano del Decoro Urbano che possa occuparsi in maniera appropriata e sistematica di una serie di problematiche come quelle sollevate dalla mancanza di senso civico. <strong>Con un Piano del decoro sar\u00e0 possibile contrastare in maniera pi\u00f9 programmata l&#8217;abusivismo, gli atti di vandalismo, l&#8217;abbandono delle carcasse di auto, tanto per fare degli esempi<\/strong>. \u201cIl Piano del decoro \u2013 ha aggiunto a questo proposito il Presidente Granata \u2013 consentir\u00e0 di prevenire e sanzionare in maniera ancora pi\u00f9 energica ogni forma di violazione\u201d. Un contributo ai lavori della commissione ambiente \u00e8 venuto dalla presenza di Giuseppina Sabato, consulente dell&#8217;Amministrazione comunale per il servizio Decoro Urbano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIl settore del decoro urbano \u2013 ha detto Sabato \u2013 \u00e8 molto vasto ed abbraccia diversi ambiti: dall&#8217;abbandono dei rifiuti, agli atti di vandalismo ed incuria, alle affissioni selvagge. Nonostante si sia sensibilmente ridotto il numero degli abbandoni dei rifiuti, molto resta ancora da fare. Fondamentali diventano l&#8217;intensificazione dell&#8217;azione di contrasto e le attivit\u00e0 di sensibilizzazione dei cittadini\u201d. Far leva sull&#8217;impegno civico, a cominciare dai consiglieri comunali che possono dare l&#8217;esempio e svolgere un ruolo fondamentale \u00e8 quello che propone la consigliera Annalisa Apicella che ha segnalato, sull&#8217;esempio di quanto avviene in altre citt\u00e0, la possibilit\u00e0 di <strong>dar vita a delle maratone di educazione civica, coinvolgendo i cittadini, con tanto di sacchetti, pinze e guanti, nella pulizia di pezzi di citt\u00e0, dove si annida maggiormente il degrado.<\/strong> \u201cLa nostra ambizione \u2013 ha aggiunto Apicella \u2013 deve essere quella di arrivare alle nuove generazioni dando noi, per primi, l&#8217;esempio\u201d. D&#8217;accordo con la collega, la consigliera comunale Francesca Cassano che ha parlato di \u201cinversione di tendenza che deve partire necessariamente dalle scuole e dalle famiglie\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La Cassano si \u00e8 anche spinta oltre proponendo, anche qui sull&#8217;esempio di quanto accade altrove, di adottare <strong>la politica di far ripulire i muri imbrattati a chi si \u00e8 reso responsabile di queste azioni. Critiche allo spazzamento in citt\u00e0 sono poi venute dal consigliere Massimo Lo Gullo<\/strong> che ha invocato una maggiore programmazione degli interventi da parte della societ\u00e0 che gestisce il servizio. Il consigliere Giuseppe D&#8217;Ippolito ha, invece, ricordato l&#8217;adozione del regolamento per la cura dei beni comuni. \u201cLa parte che guida la citt\u00e0 \u2013 ha precisato \u2013 ha gi\u00e0 approvato le misure strutturali e gli strumenti affinch\u00e9 i cittadini si rendano parte attiva nelle buone pratiche finalizzate al mantenimento del decoro urbano\u201d. La serie degli interventi \u00e8 stata conclusa dal Presidente della Commissione Ambiente del Comune di Rende, Marco Greco che ha sposato da subito l&#8217;invito rivoltogli dal collega Granata e l&#8217;idea di pensare ad un coordinamento sui regolamenti relativi al decoro urbano. Greco ha apprezzato l&#8217;avvio di un percorso comune \u201cche \u2013 ha detto \u2013 dovr\u00e0 essere seguito da ulteriori confronti, interscambi e riunioni, finalizzati non solo ad individuare gli strumenti per garantire una sempre pi\u00f9 diffusa cura e tutela del territorio, ma anche per avviare sul punto opportune campagne di sensibilizzazione e consapevolezza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verso il Piano del Decoro Urbano unico. Tra le tante proposte emerse l&#8217;organizzazione tra Rende e Cosenza di\u00a0maratone di educazione civica, coinvolgendo i cittadini, con tanto di sacchetti, pinze e guanti, nella pulizia di pezzi di citt\u00e0, dove si annida maggiormente il degrado<\/p>\n","protected":false},"author":22,"featured_media":101768,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-101767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101767"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101768"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}