{"id":101804,"date":"2018-12-09T08:47:27","date_gmt":"2018-12-09T07:47:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/torna-in-scena-la-compagnia-delle-stringhe-con-romanzata-storia-di-un-romanzo-2\/"},"modified":"2023-01-16T19:03:15","modified_gmt":"2023-01-16T18:03:15","slug":"267433-torna-in-scena-la-compagnia-delle-stringhe-con-romanzata-storia-di-un-romanzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/267433-torna-in-scena-la-compagnia-delle-stringhe-con-romanzata-storia-di-un-romanzo\/","title":{"rendered":"Torna in scena la Compagnia delle stringhe con: &#8216;Romanzata storia di un romanzo&#8217;"},"content":{"rendered":"<h4>La Compagnia delle Stringhe porta in scena\u00a0\u00a0un nuovo spettacolo,\u00a0scritto da Antonio Malfitano.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; <strong>&#8216;Romanzata storia di un romanzo&#8217;<\/strong> \u00e8 una commedia leggera con contaminazioni amare che, parafrasando il titolo, rilegge in chiave moderna l\u2019origine di un famosissimo romanzo italiano ottocentesco. Carlo \u00e8 un giovane spiantato e scansafatiche che sogna di fare lo scrittore. Talentuoso ma immaturo, ricerca nella sregolatezza l\u2019equilibrio che ancora gli manca, percorrendo l\u2019incerto confine tra giusto e sbagliato della societ\u00e0 contemporanea. Il finale rivelatore restituisce la visione d\u2019insieme.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-267439 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/12\/IMG_2922.jpg\" alt=\"\" width=\"533\" height=\"973\" title=\"\"><\/p>\n<p>I <strong>brani musicali<\/strong> sono estratti dal panorama musicale contemporaneo dedicato, e sono riarrangiati e suonati dal vivo da musicisti che fungono anche da coristi e personaggi. Il cast conta dieci interpreti ed una ballerina. Il musical, strutturato in due brevi atti, vede la luce dopo un anno di lavoro, tempo necessario per collimare la fase teatrale alla postproduzione video. Romanzata storia di un romanzo \u00e8 la sesta opera della Compagnia delle Stringhe dopo: Charitas Christi, sulla vita di San Francesco di Paola; Kalafrica , sul Risorgimento revisionista e la Questione meridionale; Ethicus , sulla censura negli anime; Magna Grecia , sulla storia della polis di Sibari; Esegesi del Cantico dei Cantici , sull\u2019origine del Cristianesimo. Questi spettacoli possono essere visionati sul sito<span style=\"color: #0000ff;\"> www.antoniomalfitano.it<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Compagnia delle Stringhe porta in scena\u00a0\u00a0un nuovo spettacolo,\u00a0scritto da Antonio Malfitano.<\/p>\n","protected":false},"author":20,"featured_media":101805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-101804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=101804"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/101804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/101805"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=101804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=101804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=101804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}