{"id":102272,"date":"2018-12-15T10:20:07","date_gmt":"2018-12-15T09:20:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/suoni-e-rumori-e-circoncolo-insieme-per-un-buon-natale-allospedale-annunziata\/"},"modified":"2023-01-16T19:03:45","modified_gmt":"2023-01-16T18:03:45","slug":"269202-suoni-e-rumori-e-circoncolo-insieme-per-un-buon-natale-allospedale-annunziata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/269202-suoni-e-rumori-e-circoncolo-insieme-per-un-buon-natale-allospedale-annunziata\/","title":{"rendered":"Suoni e Rumori e Circoncolo insieme per un &#8216;Buon Natale&#8217; all&#8217;Ospedale Annunziata"},"content":{"rendered":"<h4>I bambini del coro di voci bianche hanno portato un augurio ai malati del reparto di chirurgia pediatrica dell&#8217;ospedale Annunziata di Cosenza.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L&#8217;associazione Circoncolo nasce nel 2015 con l&#8217;intento di migliorare la qualit\u00e0 della permanenza dei pazienti nei reparti ospedalieri, attraverso l&#8217;uso dell&#8217;arte, soprattutto quella circense. Il cuore del progetto sono<strong> Valeriano Suraci<\/strong> e <strong>Ivan Cosentino<\/strong> che da anni si impegnano nel volontariato, andando avanti con le sole loro forze e con l&#8217;aiuto del 5&#215;1000. Una piccola magia, nella giornata di gioved\u00ec, fatta di emozioni e sorrisi.<em>\u00a0&#8220;I bambini hanno cantato per i bambini&#8221;<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-269203 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/12\/48355365_899644377092620_4105498756516937728_n-597x400.jpg\" alt=\"\" width=\"487\" height=\"326\" title=\"\"><\/p>\n<p><strong>Roberta Cleo<\/strong> e l&#8217;associazione <strong>Suoni e Rumori<\/strong> sono stati accolti da medici e pazienti in una atmosfera di pura serenit\u00e0, perch\u00e8 la musica e l&#8217;arte possono fare tanto e non c&#8217;\u00e8 niente di pi\u00f9 bello che regalare un sorriso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I bambini del coro di voci bianche hanno portato un augurio ai malati del reparto di chirurgia pediatrica dell&#8217;ospedale Annunziata di Cosenza.<\/p>\n","protected":false},"author":20,"featured_media":102273,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-102272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102272"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102273"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}