{"id":102419,"date":"2018-12-18T07:44:28","date_gmt":"2018-12-18T06:44:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scene-da-guerriglia-a-villa-san-giovanni-daspo-per-tifosi-catanesi-e-cosentini\/"},"modified":"2023-01-16T19:03:56","modified_gmt":"2023-01-16T18:03:56","slug":"269745-scene-da-guerriglia-a-villa-san-giovanni-daspo-per-tifosi-catanesi-e-cosentini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/269745-scene-da-guerriglia-a-villa-san-giovanni-daspo-per-tifosi-catanesi-e-cosentini\/","title":{"rendered":"Scene da guerriglia a Villa San Giovanni, Daspo per tifosi catanesi e cosentini"},"content":{"rendered":"<h4>Cinque provvedimenti di Daspo, sono stati emessi dal Questore di Reggio Calabria per tre tifosi catanesi e due cosentini<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; I cinque tifosi in questione sono ritenuti responsabili di un vero e proprio episodio di guerriglia urbana, avvenuto a seguito di un incontro, tra l&#8217;altro casuale, avvenuto a Villa San Giovanni il 3 novembre scorso durante il quale sono stati utilizzati, per l&#8217;aggressione, tubi, pietre e altri materiali. I tifosi catanesi raggiunti dal provvedimento sono: S.G.C.M., 44 anni, gi\u00e0 destinatario di due analoghi provvedimenti interdittivi, nei cui confronti il Daspo \u00e8 stato emesso per la durata di 8 anni; B.S., 27 anni, per il quale il Daspo \u00e8 stato adottato per la durata di 5 anni; Per D.B.F., 22 anni invece, avr\u00e0 una durata di 4 anni.<\/p>\n<p>Oltre al provvedimento di divieto di accesso ai luoghi dove si svolgono tutte le manifestazioni calcistiche di qualsiasi serie e categoria, \u00e8 stato anche imposto l&#8217;obbligo di presentazione presso l&#8217;Ufficio di Polizia competente per territorio mezz&#8217;ora dopo l&#8217;inizio del primo tempo e mezz&#8217;ora dopo l&#8217;inizio del secondo tempo di tutte le manifestazioni sportive nelle quali siano impegnate, a qualsiasi titolo, la compagine calcistica del &#8220;Catania Calcio&#8221;. I provvedimenti emessi a carico dei tifosi cosentini, di cui uno per 8 anni e l&#8217;altro per 5 anni, sono ancora in corso di notifica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinque provvedimenti di Daspo, sono stati emessi dal Questore di Reggio Calabria per tre tifosi catanesi e due cosentini<\/p>\n","protected":false},"author":22,"featured_media":102420,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-102419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102419"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102420"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}