{"id":102494,"date":"2018-12-19T15:23:46","date_gmt":"2018-12-19T14:23:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-rapina-a-mano-armata-nel-centro-storico\/"},"modified":"2023-01-16T19:04:01","modified_gmt":"2023-01-16T18:04:01","slug":"270149-cosenza-rapina-a-mano-armata-nel-centro-storico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270149-cosenza-rapina-a-mano-armata-nel-centro-storico\/","title":{"rendered":"Cosenza, rapina a mano armata nel centro storico"},"content":{"rendered":"<h4>In pieno giorno, armato di pistola ha fatto irruzione in farmacia portando via un bottino di circa 800 euro<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Sarebbe la prima rapina che apre le festivit\u00e0 natalizie quella compiuta ai danni di una farmacia nel centro storico consumatasi intorno alle 11 di questa mattina. Un giovane travisato da un cappuccio di una felpa, armato di pistola, un paio di occhiali a coprirgli gli occhi, ha fatto irruzione in farmacia mostrando l&#8217;arma e minacciando di usarla se i dipendenti avessero dato l&#8217;allarme. Poi sempre <strong>sotto il tiro della pistola, l&#8217;uomo ha prelevato direttamente i soldi dalla cassa.<\/strong><\/p>\n<p>Un bottino che dovrebbe aggirarsi tra le <strong>500 e le 800 euro<\/strong> ma sono ancora in corso i conteggi. Con i soldi in tasca il giovane sempre tenendo sotto tiro i dipendenti ha guadagnato la via di fuga. Il personale della farmacia ha subito dato l&#8217;allarme chiamando i carabinieri. Sul posto sono intervenuti i militari dell&#8217;Arma di Cosenza Principato diretti dal maresciallo Renato Morrone appartenenti alla compagnia cittadina agli ordini del capitano Merola.<\/p>\n<p>Dopo avere raccolto le prime testimonianze ed effettuato attivit\u00e0 investigative, in queste ore sono state prese in carico le immagini della videosorveglianza per risalire all&#8217;autore della rapina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In pieno giorno, armato di pistola ha fatto irruzione in farmacia portando via un bottino di circa 800 euro<\/p>\n","protected":false},"author":40,"featured_media":102495,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-102494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102494"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102495"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}