{"id":102558,"date":"2018-12-21T06:26:09","date_gmt":"2018-12-21T05:26:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maxi-sequestro-di-botti-natalizi-3-quintali-scoperti-nel-cosentino\/"},"modified":"2023-01-16T19:04:04","modified_gmt":"2023-01-16T18:04:04","slug":"270348-maxi-sequestro-di-botti-natalizi-3-quintali-scoperti-nel-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270348-maxi-sequestro-di-botti-natalizi-3-quintali-scoperti-nel-cosentino\/","title":{"rendered":"Maxi sequestro di botti natalizi, 3 quintali scoperti nel Cosentino"},"content":{"rendered":"<h4>Guardia di finanza al lavoro per contrastare la detenzione di fuochi pirotecnici illegalmente detenuti e pericolosi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TERRAVECCHIA (CS) &#8211; La Compagnia Guardia di Finanza di Rossano, nell\u2019ambito di un servizio finalizzato alla repressione delle violazioni nel settore della illecita detenzione e commercializzazione di fuochi pirotecnici, ha sequestrato, all\u2019interno di un magazzino nel comune di Terravecchia,<strong>\u00a0346 kg di materiale pirotecnico<\/strong> abusivamente detenuto e denunciato alla competente Autorit\u00e0 Giudiziaria<strong> un cittadino italiano ottantenne.<\/strong><\/p>\n<p>Nello specifico, i militari, hanno individuato, nelle campagne del comune di Terravecchia, un isolato magazzino che hanno inteso controllare dopo aver rilevato anomale movimentazioni di persone e mezzi. Accertata la presenza del proprietario i militari hanno fatto irruzione all\u2019interno dell\u2019immobile al fine di controllare l\u2019eventuale presenza di materiale illecito. Nel magazzino sono stati scoperti numerosi <strong>scatoloni ammassati<\/strong>, contenenti <strong>materiale pirico<\/strong> e, pertanto, hanno richiesto la certificazione autorizzatoria per la detenzione e la commercializzazione di detto materiale prevista dalla legge, del quale il soggetto \u00e8 risultato sprovvisto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-270351 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/12\/botti-sequestro-finanza-2-359x280.jpg\" alt=\"\" width=\"359\" height=\"280\" title=\"\">Tale autorizzazione, concessa direttamente dal Ministro dell\u2019Interno, \u00e8 richiesta al fine di tutelare sia l\u2019ordine pubblico che la pubblica incolumit\u00e0 e di prevenire il rischio di infortuni e incidenti. Il materiale pericoloso, \u00e8 stato sottoposto a sequestro. Si tratta di 550 pezzi tra batterie, sfere per mortai e grossi petardi. Il proprietario, un cittadino italiano <strong>ottantenne<\/strong>, \u00e8 stato deferito alla Procura della Repubblica presso il Tribunale di Castrovillari per i reati previsti e puniti dagli artt. 678 (che prevede l&#8217;arresto da tre a diciotto mesi e l&#8217;ammenda fino a 247 euro) e 679 (che prevede l\u2019arresto fino a diciotto mesi e l&#8217;ammenda fino a euro 1.000.) del Codice Penale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guardia di finanza al lavoro per contrastare la detenzione di fuochi pirotecnici illegalmente detenuti e pericolosi.<\/p>\n","protected":false},"author":22,"featured_media":102559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,1],"tags":[],"class_list":["post-102558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102558"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102559"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}