{"id":102652,"date":"2018-12-23T13:45:06","date_gmt":"2018-12-23T12:45:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/live-match-venezia-cosenza-la-gara-dei-rossoblu-in-tempo-reale\/"},"modified":"2023-01-16T19:04:12","modified_gmt":"2023-01-16T18:04:12","slug":"270657-live-match-venezia-cosenza-la-gara-dei-rossoblu-in-tempo-reale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270657-live-match-venezia-cosenza-la-gara-dei-rossoblu-in-tempo-reale\/","title":{"rendered":"(LIVE MATCH) Venezia-Cosenza 0-1 D&#8217;Orazio firma il successo dei rossoblu"},"content":{"rendered":"<h4>Venezia e Cosenza in campo allo stadio Penzo nel match valevole per la 17&#8242; giornata di campionato di Serie B<\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>FC VENEZIA (4-3-3):<\/strong> Vicario, Zampano, Domizzi, Modolo, Bruscagin, Schiavone, Bentivoglio, Segre, Di Mariano, Citro, Falzerano<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina:<\/strong> Facchin, Cernuto, Andelkovic, Garofalo, Coppolaro, Pinato, Suciu, Zennaro, Marsura, Vrioni, Litteri, St Clair<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Allenatore:<\/strong> Walter Zenga<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>COSENZA CALCIO (3-5-2):<\/strong> Perina, Corsi, Dermaku, Idda, Palmiero, Garritano, D\u2019Orazio, Maniero, Legittimo, Bruccini, Tutino<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina:<\/strong>\u00a0Cerofolini, Saracco, Pascali, Tiritiello, Schetino, Mungo, Varone, Di Piazza, Perez, Baez<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Allenatore:<\/strong> Piero Braglia<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Arbitro:<\/strong> Signor Federico Dionisi di L\u2019Aquila<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Assistenti:<\/strong> Signor Michele Grossi di Frosinone e signor Vittorio Di Gioia di Foligno<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Quarto uomo:<\/strong> Signor Nicol\u00f2 Marini di Trieste<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Note:<\/strong> Pomeriggio freddo e invernale a Venezia con una temperatura vicino ai 6 gradi. Terreno del Penzo in buone condizioni. Presenti poco pi\u00f9 di 4.000 spettatori, 250 almeno arrivati da Cosenza e sistemati nel settore di curva<\/span><\/p>\n<h4><strong><span style=\"color: #ff0000;\">LA DIRETTA DEL MATCH SI AGGIORNA IN AUTOMATICO<\/span><\/strong><\/h4>\n<p>[sls id=&#8221;2&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venezia e Cosenza in campo allo stadio Penzo nel match valevole per la 17&#8242; giornata di campionato di Serie B<\/p>\n","protected":false},"author":24,"featured_media":102653,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-102652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102652"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102653"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}