{"id":102670,"date":"2018-12-23T18:20:03","date_gmt":"2018-12-23T17:20:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/modesto-contento-a-meta-la-squadra-ha-giocato-ma-ci-e-mancata-la-cattiveria\/"},"modified":"2023-01-16T19:04:12","modified_gmt":"2023-01-16T18:04:12","slug":"270777-modesto-contento-a-meta-la-squadra-ha-giocato-ma-ci-e-mancata-la-cattiveria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270777-modesto-contento-a-meta-la-squadra-ha-giocato-ma-ci-e-mancata-la-cattiveria\/","title":{"rendered":"Modesto contento a met\u00e0 &#8220;la squadra ha giocato ma ci \u00e8 mancata la cattiveria&#8221;"},"content":{"rendered":"<h4>Il tecnico del Rende commenta il pari casalingo contro la Viterbese arrivato al termine di una partita non proprio perfetta nel quale la squadra poteva fare meglio &#8220;non mi \u00e8 piaciuto l\u2019atteggiamento. Abbiamo creato e giocato ma \u00e8 mancata cattiveria nella finalizzazione&#8221;<!--more--><\/h4>\n<p>.<\/p>\n<p>RENDE &#8211;\u00a0 Un punto guadagno o due persi? Per come si era messa la partita\u00a0 di sicuro un punto guadagnato, anche se mister Modesto recrimina per come la sua squadra ha affrontato un match che poteva aver ben altro epilogo &#8220;<em>Penso che oggi non c\u2019eravamo come atteggiamento cos\u00ec come non lo eravamo contro il Trapani. <strong>La squadra ha giocato e creato tanto, questo s\u00ec, ma \u00e8 mancata la cattiveria<\/strong> nella finalizzazione. Siamo stati bravi comunque a recuperare quel loro unico tiro in porta, ma <strong>dobbiamo essere pi\u00f9 bravi nell&#8217;ultimo passaggio<\/strong> o nella stoccata. Succede spesso e volentieri che <strong>ci mancano dei punti proprio perch\u00e9 manca l\u2019ultimo passaggio<\/strong>. Il campo non ci aiuta, la palla rimbalza male ma non deve essere un alibi. Tante volte <strong>potevamo velocizzare la giocata e invece tentavamo il dribbling<\/strong>. Ma questo ci sta anche perch\u00e9 siamo alla 18\u00aa giornata e spesso hanno giocato sempre gli stessi. <strong>Con la Viterbese comunque c&#8217;erano tanti giovani in campo<\/strong> e questa deve essere la nostra idea di Rende. Significa che i ragazzi, nonostante siano giovani, se la giocano con tutti. Un bilancio? <strong>Quello che abbiamo ottenuto finora \u00e8 merito dei ragazzi<\/strong>, che <strong>hanno sputato sangue durante gli allenamenti<\/strong> e in questa prima parte di stagione siamo stati bravi ad attenere questo bottino di punti. Ora ci fermiamo un p\u00f2 per le feste ma poi pensiamo subito alla gara contro la Paganese il 30<\/em>&#8220;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-270727\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/12\/rendeviterbese801.jpg\" alt=\"\" width=\"586\" height=\"270\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tecnico del Rende commenta il pari casalingo contro la Viterbese arrivato al termine di una partita non proprio perfetta nel quale la squadra poteva fare meglio &#8220;non mi \u00e8 piaciuto l\u2019atteggiamento. Abbiamo creato e giocato ma \u00e8 mancata cattiveria nella finalizzazione&#8221;<\/p>\n","protected":false},"author":24,"featured_media":102671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-102670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102670"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102671"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}