{"id":102708,"date":"2018-12-26T09:23:52","date_gmt":"2018-12-26T08:23:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-giuseppe-arabia-scomparso-dal-giorno-di-natale\/"},"modified":"2023-01-16T19:04:15","modified_gmt":"2023-01-16T18:04:15","slug":"270931-cosenza-giuseppe-arabia-scomparso-dal-giorno-di-natale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270931-cosenza-giuseppe-arabia-scomparso-dal-giorno-di-natale\/","title":{"rendered":"Cosenza, Giuseppe Arabia scomparso dal giorno di Natale"},"content":{"rendered":"<h4>I parenti hanno divulgato la richiesta di aiuto nelle attivit\u00e0 di ricerche tramite Facebook. Allertati i carabinieri<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; I carabinieri di Cosenza stanno cercando un anziano di 80 anni, Giuseppe Arabia, che si \u00e8 allontanato dalla sua abitazione in contrada Sant&#8217;Ippolito, alle porte della citt\u00e0. I suoi parenti hanno denunciato ieri la sua scomparsa, che risalirebbe a due giorni fa. L&#8217;uomo, che soffrirebbe di vuoti di memoria, indossava, al momento della scomparsa, un giubbotto verde scuro, un cappellino di lana e scarpe da tennis bianche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I parenti hanno divulgato la richiesta di aiuto nelle attivit\u00e0 di ricerche tramite Facebook. Allertati i carabinieri<\/p>\n","protected":false},"author":37,"featured_media":102709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-102708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102708"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102709"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}