{"id":102720,"date":"2018-12-26T17:50:31","date_gmt":"2018-12-26T16:50:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sanita-calabria-primo-intervento-di-pneumologia\/"},"modified":"2023-01-16T19:04:15","modified_gmt":"2023-01-16T18:04:15","slug":"270959-sanita-calabria-primo-intervento-di-pneumologia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/270959-sanita-calabria-primo-intervento-di-pneumologia\/","title":{"rendered":"Sanit\u00e0, Calabria: primo intervento di pneumologia"},"content":{"rendered":"<h4><strong>Asp Catanzaro: primo intervento in Calabria di pneumologia interventistica con posizionamento di drenaggio toracico a permanenza nell\u2019Ospedale di Lamezia Terme<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME (CZ) \u2013 Intervento unico in Calabria realizzato nell\u2019ospedale \u201cGiovanni Paolo II\u201d di Lamezia Terme. L\u2019equipe di pneumologia interventistica del presidio ospedaliero \u201cGiovanni Paolo II\u201d, composta dai dottori Paolo Gambardella e Salvatore Lombardo, sotto la guida del direttore della struttura complessa dott. Massimo Calderazzo, ha infatti eseguito un intervento sulla parete toracica di una paziente per il posizionamento di un catetere pleurico a permanenza con la tecnica della tunnellizzazione.<\/p>\n<p>La peculiarit\u00e0 dell\u2019intervento, condotto in collaborazione con il dott. Giuseppe Cianci dell\u2019unit\u00e0 operativa Chirurgia dello stesso nosocomio, sta nel fatto che, come si evince dai dati di letteratura scientifica, per la prima volta si utilizza tale procedura in una paziente non neoplastica affetta da gozzo intratoracico inoperabile. Un intervento delicato quanto importante, dato che nella\u00a0 letteratura internazionale non esistono casi del genere che fanno riferimento a questo tipo di intervento, su un paziente con questo quadro clinico, che attesta l\u2019alta professionalit\u00e0 e specializzazione dei medici e operatori sanitari presenti nell\u2019ospedale \u201cGiovanni Paolo II\u201d di Lamezia Terme.<\/p>\n<p>Il drenaggio a permanenza \u00e8 un dispositivo che consente di aspirare il liquido prodotto tra i foglietti pleurici in modo costante e gestibile a domicilio dagli stessi pazienti, si tratta prevalentemente di soggetti affetti da neoplasie con versamenti pleurici persistenti che necessiterebbero di periodiche toracentesi da eseguirsi presso strutture ospedaliere con notevoli costi in termini di tempi e risorse.<\/p>\n<p>Nel caso in questione la paziente, affetta da una compressione mediastinica sui vasi esercitata da un grosso gozzo intratoracico inoperabile, aveva un persistente versamento per il quale si \u00e8 optato per la soluzione permanente che consente il mantenimento in situ del drenaggio fino a 5 anni.<\/p>\n<p>L\u2019intervento, portato a termine con successo dall\u2019equipe di pneumologia interventistica si posiziona nel solco di una consolidata esperienza, ampliandone di fatto le possibilit\u00e0 operative e sottolinea come anche in provincia si possano ottenere risultati eclatanti con i pochi mezzi a disposizione rilanciando il nosocomio lametino impegnato in modo costante verso il miglioramento dei servizi erogati ed orientato alla valorizzazione delle professionalit\u00e0 del personale sanitario.<\/p>\n<p>Un dato che prova come la sanit\u00e0 in Calabria, nonostante sia considerata la cenerentola d\u2019Italia, offra delle eccellenze che meritano menzione proprio perch\u00e9 cresciute in un ambito meno favorevole.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asp Catanzaro: primo intervento in Calabria di pneumologia interventistica con posizionamento di drenaggio toracico a permanenza nell\u2019Ospedale di Lamezia Terme<\/p>\n","protected":false},"author":37,"featured_media":102721,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-102720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102720"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102721"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}