{"id":102762,"date":"2018-12-27T17:31:26","date_gmt":"2018-12-27T16:31:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tenta-la-rapina-ad-unanziana-e-fugge-dal-balcone\/"},"modified":"2023-01-16T19:04:18","modified_gmt":"2023-01-16T18:04:18","slug":"271187-tenta-la-rapina-ad-unanziana-e-fugge-dal-balcone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/271187-tenta-la-rapina-ad-unanziana-e-fugge-dal-balcone\/","title":{"rendered":"Cosenza: tenta la rapina ad un&#8217;anziana e fugge dal balcone"},"content":{"rendered":"<h4>L&#8217;ultraottantenne ha pensato bene di chiudere il rapinatore in casa per poi chiedere aiuto. Il balordo ha deciso di darsela a gambe dal balcone di casa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; E&#8217; stato un &#8220;Arsenio Lupin&#8221; sfortunato il rapinatore che ha incontrato sulla sua strada una persona, s\u00ec anziana, ma molto lucida e coraggiosa. Il fatto sarebbe accaduto tra il 22 e il 23 dicembre scorso in un&#8217;abitazione di piazza Zumbini a Cosenza. Il palazzo ha la vista principale sulla piazza ma \u00e8 dotato di un piccolo cortile interno dove ogni appartamento ha un balcone e una finestra. Il rapinatore avrebbe seguito l&#8217;anziana e poi suonando all&#8217;appartamento sarebbe penetrato all&#8217;interno chiedendo alla vittima i soldi. Per tutta risposta, l&#8217;anziana che ha problemi alla vista e quindi non riesce a distinguere bene persone e cose, ha pensato bene di rispondere al suo interlocutore di attendere che sarebbe ritornata con quanto chiesto. Invece si \u00e8 diretta verso la porta della stanza e lo avrebbe chiuso dentro a chiavi per poi correre a chiedere aiuto.<\/p>\n<p>Al rapinatore vistosi scoperto, non gli \u00e8 rimasto che tentare la fuga calandosi dal balcone che affaccia nel cortile utilizzando un lenzuolo. Inutile dire che il piano ha funzionato perch\u00e8 la distanza tra un balcone ed un altro \u00e8 minima da consentire di poter raggiungere la strada con un pizzico di scaltrezza, fortuna ed abilit\u00e0. Il balordo si \u00e8 dileguato nel nulla. Sul posto sono giunte le forze dell&#8217;ordine che in queste ore indagano sull&#8217;accaduto visionando i filmati della videosorveglianza di alcuni negozi nel tentativo di risalire all&#8217;autore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ultraottantenne ha pensato bene di chiudere il rapinatore in casa per poi chiedere aiuto. Il balordo ha deciso di darsela a gambe dal balcone di casa<\/p>\n","protected":false},"author":40,"featured_media":102763,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-102762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=102762"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/102762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/102763"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=102762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=102762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=102762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}