{"id":10384,"date":"2012-12-27T14:21:10","date_gmt":"2012-12-27T13:21:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=10384"},"modified":"2023-01-17T13:43:31","modified_gmt":"2023-01-17T12:43:31","slug":"4675-ndrangheta-sindaco-condanna-omicidio-giovane","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4675-ndrangheta-sindaco-condanna-omicidio-giovane\/","title":{"rendered":"&#8216;Ndrangheta: sindaco condanna omicidio giovane"},"content":{"rendered":"<p><strong>GIOIA TAURO<\/strong> &#8211; Il Sindaco di Gioia Tauro, Renato Bellofiore, e l&#8217;amministrazione comunale, in una nota, &#8220;esprimono dolore e grave preoccupazione per il terribile evento delittuoso che<\/p>\n<p>  <!--more-->  <\/p>\n<p>nelle prime ore del giorno di Santo Stefano ha funestato il clima di festa dell&#8217;intera comunita&#8217; gioiese. Il barbaro assassinio del giovane Francesco Bagala&#8217;, studente di appena 22 anni &#8211; si legge &#8211; ha gettato un&#8217;ombra di sconforto e di tristezza su tutta la citta&#8217; che, con fermezza, condanna un&#8217;azione cosi&#8217; efferata che ha distrutto una giovane vita&#8221;.<\/p>\n<p>Fonte AGI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO &#8211; Il Sindaco di Gioia Tauro, Renato Bellofiore, e l&#8217;amministrazione comunale, in una nota, &#8220;esprimono dolore e grave preoccupazione per il terribile evento delittuoso che<\/p>\n","protected":false},"author":22,"featured_media":10385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-10384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=10384"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/10385"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=10384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=10384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=10384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}