{"id":104305,"date":"2019-01-14T08:58:16","date_gmt":"2019-01-14T07:58:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/metrotramvia-e-traffico-cosenza-nel-caos-cittadini-esasperati\/"},"modified":"2023-01-16T18:21:20","modified_gmt":"2023-01-16T17:21:20","slug":"273181-metrotramvia-e-traffico-cosenza-nel-caos-cittadini-esasperati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/273181-metrotramvia-e-traffico-cosenza-nel-caos-cittadini-esasperati\/","title":{"rendered":"Metrotramvia e traffico: Cosenza nel caos, cittadini esasperati"},"content":{"rendered":"<h4>La protesta della citt\u00e0 \u00e8 sempre pi\u00f9 rabbiosa e costringe Mario Occhiuto a cercare di correre ai ripari<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00abIl sindaco &#8211; scrive in una nota il Comitato No Metro &#8211; sperava che sulla questione metro fosse calato il silenzio invece, purtroppo per lui, non \u00e8 cos\u00ec: in citt\u00e0 aumenta quotidianamente il caos e, di pari passo, l\u2019esasperazione della gente. La situazione \u00e8 sempre pi\u00f9 invivibile e pericolosa per la sicurezza pubblica. Dopo un mese (e solo a seguito di un nostro perentorio intervento pubblico) il primo cittadino ritorna a prendere parola sulla questione metro, continuando a dileggiare migliaia di persone. Occhiuto ha annunciato la quarta diffida nei confronti della Regione Calabria, ma ormai si \u00e8 scaduti nel ridicolo, per cui da mesi assistiamo a continui ultimatum che poi non trovano alcun seguito. Il sindaco, snobbato dai piani alti della Cittadella, <strong>invece di fare saltare il tavolo e liberare la citt\u00e0 dal cantiere fantasma e dallo spettro di una inutile e dannosa opera prosegue imperterrito a ripetere la solita stanca litania. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La novit\u00e0 \u00e8 data dal fatto che<strong> l\u2019amministrazione comunale minaccia di fare saltare l\u2019accordo relativo alla metro e di procedere autonomamente alla costruzione esclusiva del Parco del Benessere.<\/strong> Ma allora che fine ha fatto la tanto pubblicizzata vittoria politica di cui si riempiono la bocca da due anni a Palazzo dei Bruzi? Fin\u2019ora solo chiacchiere. Ed \u00e8 sempre pi\u00f9 evidente il fatto che Comune e Regione continuino a giocare ed a farsi i dispetti sulle spalle delle famiglie cosentine. Che fine hanno fatto le numerosissime dichiarazioni nelle quali si affermava che indietro non si poteva tornare, anche per via delle penali da pagare, e che tutto era ormai deciso da Comuni, Provincia e Regione? Come si vede, tutte bugie che ora vengono vergognosamente a galla. Riaprire viale Giacomo Mancini e chiudere per sempre la questione metro \u00e8 la priorit\u00e0 che i cosentini chiedono con forza ed a gran voce\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La protesta della citt\u00e0 \u00e8 sempre pi\u00f9 rabbiosa e costringe Mario Occhiuto a cercare di correre ai ripari<\/p>\n","protected":false},"author":21,"featured_media":104306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[546],"class_list":["post-104305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-metro"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104305"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104306"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}