{"id":104382,"date":"2019-01-15T18:43:31","date_gmt":"2019-01-15T17:43:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/piano-strutturale-comunale-lamministrazione-replica-a-guccione\/"},"modified":"2023-01-16T18:21:25","modified_gmt":"2023-01-16T17:21:25","slug":"273386-piano-strutturale-comunale-lamministrazione-replica-a-guccione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/273386-piano-strutturale-comunale-lamministrazione-replica-a-guccione\/","title":{"rendered":"Piano Strutturale Comunale: l&#8217;Amministrazione replica a Guccione"},"content":{"rendered":"<h4><strong>\u00a0<\/strong>\u201cL&#8217;Amministrazione comunale intende chiudere al pi\u00f9 presto il capitolo riguardante il Piano Strutturale Comunale ed \u00e8 per questa ragione che si sta completando la fase di valutazione delle osservazioni che sono state presentate da parte dei cittadini, delle aziende, delle imprese e di tutti gli stakeholders interessati\u201d<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Lo afferma l&#8217;Amministrazione comunale in risposta all&#8217;interrogazione rivolta al Sindaco Mario Occhiuto da parte del consigliere comunale Carlo Guccione in ordine a presunti inadempimenti e ritardi a suo dire ascrivibili alla Giunta comunale.<\/p>\n<p>\u201cNon c&#8217;\u00e8 nessuna Conferenza di Pianificazione da convocare \u2013 si legge nella risposta dell&#8217;Amministrazione di Palazzo dei Bruzi \u2013 perch\u00e9 abbiamo gi\u00e0 interloquito con la Regione e, come gi\u00e0 rilevato, l&#8217;iter procedurale in via di completamento riguarda la fase della valutazione delle osservazioni al Piano, gi\u00e0 avviata da tempo, e la convocazione, finalizzata alla riadozione del PSC, prima della commissione consiliare urbanistica, competente per materia, e poi dell&#8217;assemblea consiliare. Non ci sono, pertanto \u2013 come sostiene il consigliere Guccione \u2013 n\u00e9 ulteriori passaggi, n\u00e9 ritardi o inadempimenti. D&#8217;altra parte l&#8217;Amministrazione \u2013 prosegue la replica di Palazzo dei Bruzi \u2013 ha seguito sin dall&#8217;inizio la buona prassi della cos\u00ecddetta urbanistica partecipata, coinvolgendo direttamente nella discussione sul PSC, i cittadini, i professionisti e le imprese\u00a0 prima della definitiva adozione dello strumento urbanistico in Consiglio comunale, che risale alla fine di giugno del 2017.<\/p>\n<p>Ed \u00e8 per queste ragioni che l&#8217;Ufficio del Piano resta aperto e disponibile per tutte le delucidazioni che i portatori di interesse potranno ancora richiedere.<\/p>\n<p>Al consigliere Guccione rispondiamo che con orgoglio vantiamo un diritto di primogenitura per essere stata Cosenza la prima citt\u00e0 capoluogo in Calabria ad ad aver adottato un PSC con una formula nuova e con una notevole capacit\u00e0 di innovare il territorio. Negli anni passati avevamo di fronte strumenti di espansione della citt\u00e0 e che prevedevano dei volumi consistenti. L&#8217;Amministrazione comunale ha, invece,\u00a0 puntato\u00a0 molto su un Piano di rigenerazione urbana e di riqualificazione degli spazi e di recupero del centro storico. Un Piano che \u00e8 incentrato soprattutto su due obiettivi: disegnare una citt\u00e0 con dei servizi di qualit\u00e0 e creare nuove opportunit\u00e0 occupazionali. Cosenza, dopo la riadozione ed approvazione del PSC, sar\u00e0 una citt\u00e0 con pi\u00f9 servizi qualificati e una citt\u00e0 pi\u00f9 vivibile e pi\u00f9 competitiva. Per tutte queste ragioni non potremo che accelerarne e non frenarne l&#8217;iter di completamento, al contrario di quanto va sostenendo il consigliere Guccione\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u201cL&#8217;Amministrazione comunale intende chiudere al pi\u00f9 presto il capitolo riguardante il Piano Strutturale Comunale ed \u00e8 per questa ragione che si sta completando la fase di valutazione delle osservazioni che sono state presentate da parte dei cittadini, delle aziende, delle imprese e di tutti gli stakeholders interessati\u201d<\/p>\n","protected":false},"author":37,"featured_media":104383,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-104382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104382"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104383"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}