{"id":104506,"date":"2019-01-18T10:15:20","date_gmt":"2019-01-18T09:15:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/romoletto-e-il-cucciolo-perfetto-il-coraggio-dei-cani-da-salvataggio-nautico-audio\/"},"modified":"2023-01-16T18:21:33","modified_gmt":"2023-01-16T17:21:33","slug":"273733-romoletto-e-il-cucciolo-perfetto-il-coraggio-dei-cani-da-salvataggio-nautico-audio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/273733-romoletto-e-il-cucciolo-perfetto-il-coraggio-dei-cani-da-salvataggio-nautico-audio\/","title":{"rendered":"Romoletto \u00e8 il cucciolo &#8220;perfetto&#8221;. Il coraggio dei cani da salvataggio nautico (AUDIO)"},"content":{"rendered":"<h4>Romoletto \u00e8 un cucciolo perfetto e c&#8217;\u00e8 un motivo: \u00e8 educatissimo e buono. Questa settimana la rubrica Quilazampa vi racconta l&#8217;importanza dei cani per il salvataggio in acqua<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<h3>Romoletto<\/h3>\n<p>Il piccolo Romoletto \u00e8 stato sfortunato fin da quando, appena nato, \u00e8 stato abbandonato&#8230; e ancora una volta sfortunato nel restare nell&#8217;ombra per tutto questo tempo. Le volontarie quella casa, quella famiglia e l&#8217;amore di un umano glielo hanno promesso. Purtroppo fino ad oggi nessuno ha chiesto di lui, pensiamo che vedere i suoi occhi e la sua dolcezza possa servire per dargli una nuova vita. Romoletto \u00e8 molto buono, educato e la sua vita non pu\u00f2 continuare in un box nel canile. Romoletto ha circa 7 mesi \u00e8 una futura taglia media. Compatibile con i propri simili, socializzato, ama tanto le coccole ed il contatto umano. Si affida vaccinato, sterilizzato e microchippato.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-273753 size-full aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/romoletto-.jpg\" alt=\"\" width=\"419\" height=\"569\" title=\"\"><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA LA RUBRICA di questa settimana<\/span><\/h4>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/QUIZAMPAROMOLETTO.mp3&#8243;]<\/p>\n<h3>Il coraggio dei cani da salvataggio in acqua<\/h3>\n<p>Come in tutte le discipline di salvataggio, il cane grazie alle sue capacit\u00e0 fisiche e alla sua grande forza di volont\u00e0, svolge un ruolo essenziale anche come aiuto ai bagnini e ai soccorritori. Alcune tipologie di cane presentano numerose qualit\u00e0 specifiche per essere utilizzati nel salvataggio nautico (Terranova, Golden Retriver&#8230;).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-273752 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/cane-salvataggio-acqua.jpg\" alt=\"\" width=\"517\" height=\"402\" title=\"\"><\/p>\n<p>Le caratteristiche in generale sono la potenza e la forza per trainare pi\u00f9 persone o una barca di alcune tonnellate;\u00a0la resistenza che consente al cane di nuotare per molte ore e per lunghe distanze; l\u2019insensibilit\u00e0 al freddo che lo rende immediatamente operativo, al contrario di un sommozzatore che ha bisogno di circa cinque minuti per equipaggiarsi;\u00a0la calma che mantiene in ogni circostanza e la propensione di essere in grado di rassicurare pi\u00f9 di un naufrago e infine la\u00a0tenacia grazie alla quale non abbandoner\u00e0 mai la sua missione.<\/p>\n<p>Con il nome <strong>cani salvataggio nautico<\/strong> si identificano le unit\u00e0 cinofile da salvataggio in acqua. Come unit\u00e0 cinofila si intende il binomio cane-conduttore. Dagli iniziali terranova e labrador &#8220;cani bagnino&#8221; per atavica vocazione si \u00e8 riusciti nel corso degli anni a brevettare e rendere operativi centinaia di cani anche di altre razze, tra cui anche dei Pit Bull.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Se vuoi scriverci per chiedere informazioni sui cani da adottare: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3 style=\"text-align: center;\">Numeri utili per informazioni e\/o adozioni<\/h3>\n<p style=\"text-align: center;\">Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Romoletto \u00e8 un cucciolo perfetto e c&#8217;\u00e8 un motivo: \u00e8 educatissimo e buono. Questa settimana la rubrica Quilazampa vi racconta l&#8217;importanza dei cani per il salvataggio in acqua<\/p>\n","protected":false},"author":22,"featured_media":104507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[47],"tags":[],"class_list":["post-104506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104506"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104507"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}