{"id":104558,"date":"2019-01-19T11:30:13","date_gmt":"2019-01-19T10:30:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-ascoli-modifiche-alla-viabilita-in-occasione-della-gara\/"},"modified":"2023-01-16T18:21:36","modified_gmt":"2023-01-16T17:21:36","slug":"273977-cosenza-ascoli-modifiche-alla-viabilita-in-occasione-della-gara","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/273977-cosenza-ascoli-modifiche-alla-viabilita-in-occasione-della-gara\/","title":{"rendered":"Cosenza-Ascoli, modifiche alla viabilit\u00e0 in occasione della gara"},"content":{"rendered":"<h4>Divieto di transito, veicolare e pedonale, su Viale Magna Grecia per la partita Cosenza-Ascoli<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; In occasione dell\u2019incontro di calcio Cosenza-Ascoli, valevole per la 20^ giornata del campionato di Serie B, in programma allo Stadio San Vito-Marulla <strong>domani<\/strong>, domenica 20 gennaio, alle ore 15,00, il Comandante della Polizia Municipale, Giovanni De Rose, ha emanato un\u2019ordinanza per motivi di ordine pubblico e per disciplinare l&#8217;afflusso allo stadio ed il conseguente deflusso delle due tifoserie, in modo separato, in tempi rapidi e senza rischi per la pubblica incolumit\u00e0.<\/p>\n<p><strong>La viabilit\u00e0 verr\u00e0 disciplinata nel modo seguente:<\/strong><\/p>\n<p>su Vale Magna Grecia, in entrambi i sensi di marcia, nel tratto compreso tra la Rotonda di raccordo con la ex SS19 Bis e la rotonda all\u2019altezza del ponte per Castrolibero, viene istituito il divieto di transito veicolare e pedonale, dalle ore 13:00 fino alle ore 19:00 del 20 genanio 2019 e comunque fino a cessate esigenze.<\/p>\n<p>Gli agenti preposti al controllo, potranno estendere o modificare le disposizioni di cui al presente atto in base a sopraggiunte ed imprevedibili necessit\u00e0 di ordine pubblico, di sicurezza, di variazione dei flussi di traffico ed altre contingenze;<\/p>\n<p><strong>Si consigliano i seguenti tragitti alternativi:<\/strong><\/p>\n<p>-I veicoli provenienti o diretti a Castrolibero potranno percorrere via Degli Stadi;<br \/>\n-I veicoli diretti a Rende potranno percorrere via Panebianco;<br \/>\n-I pedoni per raggiungere lo stadio dovranno percorrere via degli Stadi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Divieto di transito, veicolare e pedonale, su Viale Magna Grecia per la partita Cosenza-Ascoli<\/p>\n","protected":false},"author":22,"featured_media":104559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-104558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104558"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104559"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}