{"id":104685,"date":"2019-01-22T11:40:51","date_gmt":"2019-01-22T10:40:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/licenziamenti-nei-call-center-solidarieta-ai-lavoratori-comdata\/"},"modified":"2023-01-16T18:21:45","modified_gmt":"2023-01-16T17:21:45","slug":"274477-licenziamenti-nei-call-center-solidarieta-ai-lavoratori-comdata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/274477-licenziamenti-nei-call-center-solidarieta-ai-lavoratori-comdata\/","title":{"rendered":"Licenziamenti nei call center, solidariet\u00e0 ai lavoratori Comdata"},"content":{"rendered":"<h4>Denunciate le condizioni degli operatori cui\u00a0stipendio medio \u00e8 troppo basso persino per poter arrivare a vivere dignitosamente fino a met\u00e0 del mese<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; &#8220;Sciopero nei call center: chi tocca uno, tocca tutti. Il Partito Comunista si schiera al fianco dei lavoratori della sede rendese di Comdata che scioperano in solidariet\u00e0 ai propri colleghi, che in queste drammatiche ore &#8211; ricordano gli attivisti del partito in una nota &#8211; rischiano il licenziamento. La sede di Pozzuoli risulta praticamente gi\u00e0 chiusa, mentre gli operatori di Padova, Livorno, Ivrea e Olbia stanno per andare incontro a centinaia di licenziamenti. Riteniamo inammissibile che questi &#8216;imprenditori&#8217; possano ledere in maniera cos\u00ec violenta i diritti dei lavoratori, imponendo da una parte licenziamenti di massa e dall\u2019altra un sistema di sorveglianza a distanza che sembra replicare i metodi di controllo degli schiavi nelle piantagioni. <strong>La continua sete di denaro e profitti della multinazionale Comdata (che gi\u00e0 fattura circa un miliardo di euro all\u2019anno) non ha limiti<\/strong> e ci\u00f2 \u00e8 reso evidente dalle lamentele per i salari dei lavoratori che risulterebbero troppo alti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Noi siamo invece coscienti che<strong> lo stipendio medio di un operatore di call center \u00e8 troppo basso persino per poter arrivare a vivere dignitosamente fino a met\u00e0 del mese.\u00a0<\/strong>Il settore delle telecomunicazioni \u00e8 da sempre un laboratorio dove poter sperimentare nuove forme di sfruttamento e umiliazione dei lavoratori, attraverso il ricorso a contratti precari ed a commesse provenienti dalle grandi imprese, che riducono diritti e stipendi degli operatori, per garantire immensi guadagni alle agenzie interinali ed ai proprietari dei call center. Le pi\u00f9 grandi armi con le quali noi possiamo difendere la nostra dignit\u00e0 di lavoratori sono la solidariet\u00e0, la complicit\u00e0 tra tutti i colleghi e gli scioperi. Sappiamo bene che sono solo le nostre braccia e le nostre menti a garantire la produzione ed i profitti. Il Partito Comunista \u00e8 composto da disoccupati, precari, operai e non possiamo fare altro che sostenere con tutta la nostra forza i lavoratori che lottano per il proprio avvenire. Proprio per tale motivo rivendichiamo il blocco immediato dei licenziamenti e delle strategie di controllo a distanza, l\u2019aumento dei posti di lavoro, la riduzione dell\u2019orario di lavoro a parit\u00e0 di salario, la fine delle esternalizzazioni e degli appalti con la contestuale assunzione a tempo pieno e indeterminato di tutti i lavoratori delle telecomunicazioni presso le rispettive aziende appaltanti. Il lavoro non si tocca&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Denunciate le condizioni degli operatori cui\u00a0stipendio medio \u00e8 troppo basso persino per poter arrivare a vivere dignitosamente fino a met\u00e0 del mese<\/p>\n","protected":false},"author":21,"featured_media":104686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-104685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104685"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104686"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}