{"id":104701,"date":"2019-01-22T16:58:43","date_gmt":"2019-01-22T15:58:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/meteo-cosenza-impulso-polare-e-ciclone-mediterraneo-piogge-e-copiose-nevicate-in-arrivo\/"},"modified":"2023-01-16T18:21:46","modified_gmt":"2023-01-16T17:21:46","slug":"274527-meteo-cosenza-impulso-polare-e-ciclone-mediterraneo-piogge-e-copiose-nevicate-in-arrivo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/274527-meteo-cosenza-impulso-polare-e-ciclone-mediterraneo-piogge-e-copiose-nevicate-in-arrivo\/","title":{"rendered":"Meteo Cosenza, impulso polare e ciclone Mediterraneo: piogge e copiose nevicate in arrivo"},"content":{"rendered":"<h4>Meteo in ulteriore e deciso peggioramento tra mercoled\u00ec e gioved\u00ec per l&#8217;arrivo di correnti polari responsabili della formazioni di un profondo minimo in rotta verso il basso Tirreno. Sulla Calabria attese piogge, temporali e abbondati nevicate in montagna<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;<strong><span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5879\" target=\"_blank\" rel=\"noopener\">Dopo il gelo e la neve<\/a><\/span><\/strong>\u00a0di due settimane fa e gli ultimi giorni caratterizzato dal clima stabile e soleggiato, grazie alla\u00a0<strong>protezione dell&#8217;anticiclone delle Azzorre<\/strong>, il tempo sulla Calabria, cos\u00ec come su buona parte delle regioni centro\/meridionali, \u00e8 decisamente mutato al brutto tempo a causa dell&#8217;arrivo di una perturbazione atlantica responsabile di un primo peggioramento che sta portando rovesci intesi, piogge e qualche temporale con un <strong>vortice di bassa pressione<\/strong> presente sul medio e basso versante tirrenico.<strong> Sui rilievi di Sila e Pollino la pioggia si \u00e8 trasformata in neve<\/strong> caduta a quote medio\/alte. <strong>Fiocchi questa mattina intorno ai 1.200\/1.300 metri<\/strong>, mentre su parte del centro Italia la neve ha raggiunto anche le quote di bassa collina. Sulla Calabria spirano venti di libeccio. Dalla serata temperatura <strong>destinata a scendere di qualche grado<\/strong> con quota neve in calo fino ai 1.000\/1.200 metri.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-274539\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/Ciclone-Mediterrano-venti.jpg\" alt=\"\" width=\"583\" height=\"314\" title=\"\"><\/p>\n<h4>Aria polare in rotta verso il Mediterraneo. Piogge, temporali e tanta neve<\/h4>\n<p>Ma il vero peggioramento sulla Calabria \u00e8 atteso tra la giornata di domani ma sopratutto di gioved\u00ec, quando <strong>irromper\u00e0 nel Mediterraneo un nucleo freddo di originale polare<\/strong>\u00a0dalla porta del Rodano, responsabile della formazione di un <strong>profondo minimo d bassa pressione<\/strong> sulla Sardegna in movimento verso il basso Tirreno, il Canale di Sicilia e l&#8217;Egeo. La <strong>profonda area ciclonica <\/strong>(previsti valori\u00a0 tra i 970 e 980 hPa) presenta i connotati di un vero e proprio<strong> ciclone Mediterraneo <\/strong>con\u00a0venti intesi e <b>raffiche tra la Sardegna\u00a0e la Sicilia anche a 80 Km\/h<\/b>, ma sopratutto <strong>intense precipitazioni anche temporalesche<\/strong> che interesseranno gioved\u00ec buona parte della nostra regione.<\/p>\n<p>Piogge, mare grosso e temporali in pianura,<strong> neve abbondante su Sila con quota intorno 1.000\/1.200 metri<\/strong>, pi\u00f9 <strong>in basso sul Pollino<\/strong>. Gioved\u00ec potrebbero cadere anche<strong> 50 cm di neve<\/strong> e man mano che il minimo tender\u00e0 a traslare verso est, irromper\u00e0 aria sempre pi\u00f9 fredda. Tra venerd\u00ec e sabato tempo ancora instabile con precipitazioni che potrebbero <strong>assumere carattere nevoso anche a quote medio basse<\/strong> (500\/700 metri).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meteo in ulteriore e deciso peggioramento tra mercoled\u00ec e gioved\u00ec per l&#8217;arrivo di correnti polari responsabili della formazioni di un profondo minimo in rotta verso il basso Tirreno. Sulla Calabria attese piogge, temporali e abbondati nevicate in montagna<\/p>\n","protected":false},"author":22,"featured_media":104702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[221],"tags":[],"class_list":["post-104701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-previsioni-meteo-per-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104701"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104702"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}