{"id":104880,"date":"2019-01-26T12:17:09","date_gmt":"2019-01-26T11:17:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/usava-anche-il-figlio-come-tramite-per-le-minacce-alla-moglie-arrestato\/"},"modified":"2023-01-16T18:21:58","modified_gmt":"2023-01-16T17:21:58","slug":"275074-usava-anche-il-figlio-come-tramite-per-le-minacce-alla-moglie-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275074-usava-anche-il-figlio-come-tramite-per-le-minacce-alla-moglie-arrestato\/","title":{"rendered":"Usava anche il figlio come tramite per le minacce alla moglie, arrestato"},"content":{"rendered":"<h4>Ancora un caso di violenza domestica, di persecuzione caratterizzato da minacce che venivano veicolate anche utilizzando il proprio figlio. All&#8217;uomo \u00e8 stata notificata un&#8217;ordinanza di applicazione di misura cautelare agli arresti domiciliari emessa dal tribunale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Ancora un caso di violenza, di minacce e molestie nei confronti di una donna, una moglie costretta ad essere persino controllata in ogni suo movimento. Una vicenda ricostruita dai carabinieri della Stazione di Lido che hanno arrestato <strong>C.S.D., 38enne<\/strong> catanzarese, gi\u00e0 noto alle forze dell\u2019ordine.<\/p>\n<p>Episodi che nelle ultime settimane erano diventati sempre pi\u00f9 frequenti:\u00a0 condotte di violenza, minaccia e molestia ai danni della propria consorte. In un caso, lo scorso 31 dicembre, ad esempio, l\u2019uomo avrebbe letteralmente inondato\u00a0<strong>la moglie con chiamate, sms e messaggi vocali<\/strong> dal <strong>contenuto minatorio<\/strong> e vessatorio, oltre che gravemente offensivo della dignit\u00e0 e del decoro della persona.<\/p>\n<p>Una serie infinita di chiamate e messaggi, che non hanno risparmiato neanche il figlio minore, utilizzato quale &#8220;<strong>strumento&#8221; di informazione<\/strong> sugli spostamenti e le frequentazioni della vittima. Ancora, solo pochi giorni fa, altre chiamate, numerose, in cui la stessa ha subito gravi ed inaccettabili <strong>minacce di morte<\/strong>. Il giudice ha adottato il provvedimento restrittivo, immediatamente eseguito dai militari dell&#8217;Arma per interrompere l&#8217;escalation di violenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora un caso di violenza domestica, di persecuzione caratterizzato da minacce che venivano veicolate anche utilizzando il proprio figlio. All&#8217;uomo \u00e8 stata notificata un&#8217;ordinanza di applicazione di misura cautelare agli arresti domiciliari emessa dal tribunale<\/p>\n","protected":false},"author":42,"featured_media":104881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-104880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104880"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104881"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}