{"id":104965,"date":"2019-01-28T22:11:16","date_gmt":"2019-01-28T21:11:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-che-rimonta-a-verona-da-0-2-a-2-2-firmato-sciaudone-e-idda\/"},"modified":"2023-01-16T18:22:04","modified_gmt":"2023-01-16T17:22:04","slug":"275342-cosenza-che-rimonta-a-verona-da-0-2-a-2-2-firmato-sciaudone-e-idda","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275342-cosenza-che-rimonta-a-verona-da-0-2-a-2-2-firmato-sciaudone-e-idda\/","title":{"rendered":"Cosenza che rimonta a Verona! Da 0-2 a 2-2 firmato Sciaudone e Idda"},"content":{"rendered":"<h4>I rossoblu portano a casa un pareggio che vale oro, mandano in brodo di giuggiole i 400 tifosi presenti al Bentegodi. Tupta nel primo tempo e Di Carmine a met\u00e0 ripresa portano avanti\u00a0 il Verona. Ma il Cosenza non si arrende e nel giro di 3&#8242; minuti accorcia con Sciaudone e pareggia con Idda\u00a0<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>VERONA &#8211; <span style=\"color: #000000;\">Il Cosenza <strong>strappa un preziosissimo pareggio<\/strong> nella difficile trasferta di Verona, riprendendosi in parte quando perso nella gara di andata non disputata al Marulla e persa a tavolino. E&#8217; stata una gara dai due volti quella dei rossoblu<strong>, timidi e impacciati nel primo tempo <\/strong>(nonostante i 4 attaccanti schierati dal 1&#8242; minuto)<strong>, volitivi e determinati nella ripresa<\/strong> che a un certo punto sembrava segnata con il <strong>raddoppio messo a segno da Di Carmine al 71&#8242;<\/strong> dopo il <strong>vantaggio arrivato nella prima frazione con Tupta<\/strong>. E invece mago Braglia ancora una volta azzecca i cambi giusti e il <strong>Cosenza nel giro di 3&#8242; minuti ribalta la gara, <\/strong>prima accorciando le distanze proprio<strong> con il nuovo arrivato Sciaudone<\/strong> che di testa indirizza nell&#8217;angolo basso un cross al bacio dell&#8217;altro neo entrato D&#8217;Orazio ed <strong>esulta alla Cristiano Ronaldo<\/strong>. <strong>Il Verona arretra e i rossoblu ne approfittano trovando il pareggio<\/strong>\u00a0a 5&#8242; minuti dal termine <strong>grazie alla deviazione vincente di Idda<\/strong> che manda in delirio i 400 tifosi del Cosenza. Il difensore rossoblu \u00e8 poi miracoloso nel deviare una conclusione di Matos a botta sicura, mentre Perina in pieno recupero ci mette i guantoni sulla botta di Dawidowicz.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-275369\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/tutino.jpg\" alt=\"\" width=\"593\" height=\"333\" title=\"\"><\/p>\n<h4><span style=\"color: #000000;\">Embalo dal 1&#8242; minuto ma \u00e8 un Cosenza impacciato<\/span><\/h4>\n<p><span style=\"color: #000000;\"><strong>Primo tempo praticamente dominato dal Verona<\/strong>\u00a0con il Cosenza che fatica a costruire gioco e a proporsi in avanti, nonostante una squadra super offensiva nel quale figura Embalo, buttato subito nella mischia da Braglia, ma ancora lontano dalla forma migliore e soprattutto dai meccanismi della squadra. Gli avanti rossoblu pungono poco, mentre dall&#8217;altra parte il tridente del Verona mette in costante apprensione la retroguardia del Cosenza.\u00a0<strong>Al 21&#8242; Perina deve metterci una pezza<\/strong>\u00a0sulla conclusione di Pazzini che\u00a0<strong>poco dopo la mezzora propizia il vantaggio<\/strong>\u00a0<strong>dei padroni di casa<\/strong>: sventola in diagonale disinnescata da Perina. Il pallone per\u00f2 rimane nell&#8217;area piccola con i difensori del Cosenza che si impappinano.<strong>\u00a0Il pi\u00f9 lesto di tutti \u00e8 l&#8217;attaccante sloveno\u00a0Tupta<\/strong>\u00a0che in scivolata anticipa Idda e insacca. La reazione del Cosenza \u00e8 nel\u00a0<strong>destro al volo di Bruccini<\/strong>\u00a0che fa la barba al palo. Ma \u00e8 sempre il Verona a creare pericoli alla porta di Perina che prima vede il <strong>destro di Colombatto uscire di un nulla<\/strong>, poi <strong>ci mette i guantoni per deviare il destro di Pazzini dal limite<\/strong> proprio in chiusura di tempo.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-275373\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/Tifosi-Cosenza1.jpg\" alt=\"\" width=\"513\" height=\"296\" title=\"\"><\/p>\n<h4><span style=\"color: #000000;\">Di Carmine raddoppia. Poi rimonta firmata Sciaudone, Idda<\/span><\/h4>\n<p><span style=\"color: #000000;\">La ripresa vede in campo un Cosenza decisamente pi\u00f9 propositivo<strong> alla conclusione al 47&#8242; con un diagonale di Legittimo<\/strong> deviato in angolo. L<strong>&#8216;occasione del pareggio capita per\u00f2 al minuto 52&#8217; sui piedi di Tutino<\/strong>. L&#8217;attaccante, servito alla perfezione da Mungo, spara a di piatto in corsa trovando la grandissima risposta di Silvestri. Grosso capisce che bisogna cambiare e sostituisce due terzi del reparto offensivo inserendo Martos e Di Carmine. E <strong>proprio l&#8217;ex attaccante del Perugia trova il raddoppio al 71&#8242;<\/strong> scaraventando in rete in diagonale, il pallone deviato da Perina su conclusione di\u00a0Bianchetti. Gara finita? Nemmeno per sogno perch\u00e9 <strong>il neo entrato Sciaudone bagna il suo esordio in maglia rossoblu trovando la rete del 2 a 1<\/strong> con una precisa incornata di testa su cross di D&#8217;Orazio. L&#8217;inerzia passa tutta al Cosenza che<strong> al minuto 85&#8242; trova il pareggio con la deviazione sottoporta di Idda<\/strong> su assist di Dermaku. Il Verona schiuma rabbia e si riversa in avanti <strong>sfiorando il 3 a 2 con Matos<\/strong> (miracolosa la deviazione di Idda) e con<strong>\u00a0Dawidowicz stoppato dal solito grande Perina<\/strong>. Poi il triplice fischio finale con i cori dei 400 tifosi del Cosenza e i fischi dei tifosi veronesi.<\/span><\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><span style=\"color: #000000;\"><strong>HELLAS VERONA (4-3-3):\u00a0<\/strong>Silvestri, Bianchetti, Marrone, Dawidowicz, Faraoni, Colombatto, Gustafson, Zaccagni (75&#8242; Danzi), Tupta, Pazzini (66&#8242; Di Carmine), Di Gaudio (65&#8242; Matos)<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina: <\/strong>Berardi, Ferrari, Henderson, Matos, Di Carmine, Balkovec, Lee, Ciss\u00e9, Laribi, Danzi, Almici, Empereur<\/span><br \/>\n<span style=\"color: #000000;\"> <strong>Allenatore:<\/strong> Fabio Grosso<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>COSENZA CALCIO (4-4-2):<\/strong> Perina, Corsi, Dermaku, Idda, Embalo (65&#8242; Sciaudone), Mungo, Legittimo (69&#8242; D&#8217;Orazio), Maniero (69&#8242; Perez), Bruccini, Tutino, Baez<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Panchina: <\/strong>Saracco, Capela, Perez, Palmiero, D\u2019Orazio, Schetino, Sciaudone, Pascali<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Allenatore:<\/strong> Piero Braglia<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Arbitro: <\/strong>Signor Antonio Rapuano di Rimini<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Assistenti: <\/strong>Signor\u00a0Marco Chiocchi di Foligno e signor Giovanni Luciano\u00a0di Lamezia Terme<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Quarto uomo: <\/strong>Signor\u00a0Davide Miele di Torino<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Ammoniti: <\/span><\/strong><span style=\"color: #000000;\">Embalo (C), Mungo (C), Sciaudone (C), Matos (V), D&#8217;Orazio (C), Marrone (V)<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Espulsi:<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #000000;\">Angoli: <\/span><\/strong><span style=\"color: #000000;\">6<\/span><span style=\"color: #000000;\">-6<\/span><\/p>\n<p><strong><span style=\"color: #000000;\">Recupero: <\/span><\/strong><span style=\"color: #000000;\">1&#8242; p.t<\/span><strong><span style=\"color: #000000;\"> &#8211;<\/span><\/strong><span style=\"color: #000000;\"> 5&#8242; s.t.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Note: <\/strong>Serata fredda e invernale a Verona con temperatura vicino ai 2 gradi. Terreno del Bentegodi in ottime condizioni. Presenti poco pi\u00f9 d 9.000 spettatori, 400 dei quali tifosi del Cosenza sistemati nel settore ospiti<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rossoblu portano a casa un pareggio che vale oro, mandano in brodo di giuggiole i 400 tifosi presenti al Bentegodi. Tupta nel primo tempo e Di Carmine a met\u00e0 ripresa portano avanti\u00a0 il Verona. Ma il Cosenza non si arrende e nel giro di 3&#8242; minuti accorcia con Sciaudone e pareggia con Idda\u00a0<\/p>\n","protected":false},"author":23,"featured_media":104966,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-104965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104965"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104966"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}