{"id":104998,"date":"2019-01-29T14:32:09","date_gmt":"2019-01-29T13:32:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/milioni-di-euro-per-le-imprese-calabresi\/"},"modified":"2023-01-16T18:22:05","modified_gmt":"2023-01-16T17:22:05","slug":"275495-milioni-di-euro-per-le-imprese-calabresi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275495-milioni-di-euro-per-le-imprese-calabresi\/","title":{"rendered":"Milioni di euro per le imprese calabresi, convegno l&#8217;8 febbraio (AUDIO)"},"content":{"rendered":"<h4>Oltre due miliardi di euro di fondi pubblici a sostegno delle aziende. Incontro a Cosenza per illustrare tutte le nuove opportunit\u00e0 e le istruzioni per accedere ai finanziamenti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Milioni di euro a disposizione delle imprese calabresi. \u00c8 di oltre 2 miliardi di euro l\u2019ammontare delle risorse pubbliche destinate a sostenere aziende gi\u00e0 esistenti e nuove idee imprenditoriali, soprattutto al Sud. Opportunit\u00e0 di finanziamento spesso ignorate dagli stessi interessati. Proprio per diffondere la conoscenza di tutti gli strumenti e gli incentivi alle imprese calabresi \u00e8 stato organizzato un convegno da Cia-Agricoltori italiani Calabria Nord, con la partecipazione di Manageritalia Puglia Calabria e Basilicata. L\u2019incontro dal titolo <strong>\u201cIncentivi e strumenti di sostegno alle imprese: bandi attuali e prospettive future\u201d si terr\u00e0 presso la sala Mancini della Camera di commercio di Cosenza l\u20198 febbraio 2019 alle 16:00.\u00a0<\/strong>Diverse le tipologie di finanziamento che verranno illustrate. Resto al Sud che sostiene la nascita di nuove imprese nelle regioni del Mezzogiorno e la cui dotazione finanziaria complessiva \u00e8 di 1.250 milioni di euro. Con la legge del bilancio 2019 si allarga la platea dei destinatari estesa anche agli under 46 e ai liberi professionisti.<\/p>\n<p><strong>Luca Pignataro<\/strong> presidente di CIA Calabria Nord e <strong>Savino Magno<\/strong>, Executive Professional di Manager Italia, hanno illustrato obiettivi e finalit\u00e0 del convegno ai microfoni di <strong>RLB<\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-104998-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/CIA.mp3?_=1\" \/><a href=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/CIA.mp3\">https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/CIA.mp3<\/a><\/audio>\n<p>C\u2019\u00e8 poi il Psr 2014\/2020, il<strong> Programma di sviluppo rurale. L\u2019Unione europea mette a disposizione della regione Calabria risorse finanziarie per oltre 1.100 milioni di euro.<\/strong> La Camera di commercio di Cosenza prevede la concessione di contributi, a favore di imprese anche agricole, per la partecipazione a fiere ed eventi. L&#8217;investimento deve essere massimo di 10 mila euro e ne viene rimborsato il 50%. Oltre 5 milioni di euro per il Fondo artigiano Regione Calabria, misura di aiuto finalizzata alla concessione contributi in conto interessi e in conto capitale in favore delle imprese calabresi. Macchinari innovativi \u00e8 l\u2019agevolazione messa a disposizione dal ministero dello Sviluppo economico, piano nazionale \u201cImpresa 4.0\u201d, con l\u2019obiettivo di sostenere le aziende delle regioni meno sviluppate (Basilicata, Calabria, Campania, Puglia e Sicilia).<\/p>\n<p><strong>La dotazione finanziaria complessiva \u00e8 di oltre 340 milioni.<\/strong> Voucher innovation manager, novit\u00e0 introdotta dalla Legge di bilancio 2019, che consiste nella consulenza di un esperto per ammodernare gli assetti gestionali e organizzativi dell\u2019impresa, compreso l\u2019accesso ai mercati finanziari e dei capitali. Il valore massimo del progetto \u00e8 pari a 40 mila euro con un contributo fino al 50% dei costi sostenuti nel 2019 e nel 2020. \u00c8 di 35 milioni di euro il totale dei contributi a fondo perduto messi a disposizione dal Bando ISI 2018 alle imprese agricole, con contributo in conto capitale fino al 50% dei costi sostenuti per la realizzazione dell\u2019intervento e fino a un massimo di 60 mila euro, ed ulteriori 335 milioni di euro di finanziamento a fondo perduto per tutte le altre imprese, con un contributo in conto capitale fino al 65% Maurizio Di Domenico, executive manager certificato di Federmanager, illustrer\u00e0 gli incentivi e gli strumenti di sostegno per le imprese del Sud Italia (bando macchinari innovativi, voucher innovation manager, novit\u00e0 sul bando Resto al sud, ecc..). Rosella Di Benedetto (coordinatore Contarp Inail Calabria) elencher\u00e0 le opportunit\u00e0 del bando Isi Inail 2018 con un incremento della dotazione finanziaria per la Calabria pari al 40% in pi\u00f9 rispetto all\u2019anno precedente.<\/p>\n<p>Savino Magno, executive professional Manageritalia e commercialista esperto in finanza agevolata, presenter\u00e0 alcuni casi aziendali. Fabio Raccosta, responsabile nazionale servizi per le imprese Cia, evidenzier\u00e0 gli aspetti della sicurezza del lavoro in agricoltura, Giacomo Giovinazzo, direttore generale dipartimento Agricoltura della regione Calabria, relazioner\u00e0 sugli strumenti di programmazione e finanziamento Psr 2014-2020 soffermandosi sulle opportunit\u00e0 presenti e future per le aziende calabresi<strong>.<\/strong> Gli strumenti e gli incentivi alle imprese promosse dalla Regione Calabria saranno esaminati da Francesco Russo, assessore allo Sviluppo economico mentre Erminia Giorno, segretario generale Camera di commercio Cosenza, approfondir\u00e0 il ruolo della Camera per le imprese in provincia di Cosenza illustrando i bandi in corso e di prossima uscita. I lavori saranno coordinati dal caporedattore Tgr Rai Calabria, Luca Ponzi. <strong>La partecipazione al convegno sar\u00e0 un momento di crescita sia per i professionisti che per gli imprenditori operanti in vari settori, permettendo di affinare la conoscenza dei pi\u00f9 recenti strumenti a disposizione delle imprese<\/strong> per lavorare in sicurezza e migliorarne la competitivit\u00e0.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-275500 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/cia-cosenza.jpg\" alt=\"\" width=\"472\" height=\"678\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oltre due miliardi di euro di fondi pubblici a sostegno delle aziende. Incontro a Cosenza per illustrare tutte le nuove opportunit\u00e0 e le istruzioni per accedere ai finanziamenti<\/p>\n","protected":false},"author":43,"featured_media":104999,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42,572,16,28,61,576],"tags":[586],"class_list":["post-104998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza","category-ionio","category-italia","category-provincia","category-tecnologia-e-internet","category-tirreno","tag-lavoro"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=104998"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/104998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/104999"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=104998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=104998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=104998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}