{"id":105035,"date":"2019-01-30T09:07:09","date_gmt":"2019-01-30T08:07:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/gente-senza-casa-e-case-senza-gente-la-soluzione-per-i-senzatetto\/"},"modified":"2023-01-16T18:22:07","modified_gmt":"2023-01-16T17:22:07","slug":"275617-gente-senza-casa-e-case-senza-gente-la-soluzione-per-i-senzatetto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275617-gente-senza-casa-e-case-senza-gente-la-soluzione-per-i-senzatetto\/","title":{"rendered":"Gente senza casa e case senza gente, la soluzione per i senzatetto"},"content":{"rendered":"<h4>Italiani e migranti costretti a vivere in condizioni abitative drammatiche, in strada, in baraccopoli, in auto. Un corposo gruppo di persone aderisce al Comitato per il riutilizzo delle case vuote per superare uno dei tanti paradossi calabresi\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN FERDINANDO (RC) &#8211; Venerd\u00ec 1 febbraio si terr\u00e0 una importante iniziativa presso il Comune di San Ferdinando: la costituzione del Comitato per il riutilizzo delle case vuote della Piana da parte dei lavoratori locali e migranti. &#8220;Le condizioni degradanti in cui sono costretti a vivere i braccianti nel nostro territorio sono qualcosa di inaccettabile, &#8211; scrive in una nota Potere al Popolo Calabria &#8211; la chiusura del ghetto un&#8217;impellenza. Ma la risposta a questa vergogna non \u00e8 non pu\u00f2 essere la ruspa, soprattutto in una regione come la nostra, in cima alla speciale classifica del vuoto abitativo: il 40% delle case in Calabria sono vuote, 35mila case di queste solo nella Piana di Gioia Tauro.<br \/>\nBasta quindi a misure emergenziali, basta a tutte le polemiche tese a fomentare la guerra tra poveri. Il dato del patrimonio immobiliare vuoto p<strong>ermette di affrontare nel nostro territorio il problema del disagio abitativo per tutti, italiani e stranieri, senza n\u00e9 un prima n\u00e9 un dopo perch\u00e9 le case ci sarebbero per tutti.<\/strong> L\u2019incentivo all\u2019affitto attraverso l\u2019istituzione del fondo di garanzia \u00e8 un primo passo importante in questa direzione. Come Potere al Popolo! ci impegneremo all\u2019interno del Comitato per sostenere questa strada, che non \u00e8 solo una risposta al dramma della tendopoli, ma deve essere una opportunit\u00e0 per tutta la Piana di Gioia Tauro, per ridare dignit\u00e0, diritti e servizi ai centri interni, per inseguire quegli effetti positivi prodotti dai \u201cnuovi cittadini\u201d che si sono realizzati a Riace e in tante altre esperienze positive&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italiani e migranti costretti a vivere in condizioni abitative drammatiche, in strada, in baraccopoli, in auto. Un corposo gruppo di persone aderisce al Comitato per il riutilizzo delle case vuote per superare uno dei tanti paradossi calabresi\u00a0<\/p>\n","protected":false},"author":43,"featured_media":105036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105035"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105036"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}