{"id":105055,"date":"2019-01-30T15:30:39","date_gmt":"2019-01-30T14:30:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/blitz-antibracconaggio-nel-cosentino-denunce-sequestri-e-perquisizioni\/"},"modified":"2023-01-16T18:22:09","modified_gmt":"2023-01-16T17:22:09","slug":"275679-blitz-antibracconaggio-nel-cosentino-denunce-sequestri-e-perquisizioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275679-blitz-antibracconaggio-nel-cosentino-denunce-sequestri-e-perquisizioni\/","title":{"rendered":"Blitz antibracconaggio nel cosentino: denunce, sequestri e perquisizioni"},"content":{"rendered":"<h4>Una vasta operazione della Polizia Provinciale \u00e8 stata messa in campo nell&#8217;ambito di una mirata attivit\u00e0 di prevenzione e repressione dei reati in materia venatoria<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN GIOVANNI IN FIORE (CS) &#8211; La Polizia Provinciale di Cosenza, sotto le direttive del comandante dott. Pasquale Monea e del Sostituto Commissario Maria Antonietta Pignataro, nei giorni scorsi ha effettuato alcuni mirati interventi che hanno portato alla <strong>denuncia di due persone<\/strong> e al <strong>sequestro di un\u2019arma, di munizioni detenute illegalmente e di selvaggina non cacciabile per il periodo<\/strong>. Gli agenti in servizio presso il distaccamento di San Giovanni in Fiore si sono recati in <strong>varie localit\u00e0<\/strong> situate tra i Comuni <strong>di San Giovanni in Fiore, Casali del Manco, Spezzano della Sila, Acri, San Demetrio Corone e Santa Sofia d\u2019Epiro.<\/strong><\/p>\n<p>All\u2019interno di alcune campagne del cosentino \u00e8 stato individuato un uomo che, al termine di una battuta di caccia eseguita con altre <strong>tre persone<\/strong>, aveva <strong>abbattuto<\/strong> alcuni esemplari di avifauna appartenenti alla specie Merlo (Turdus merula). Secondo il vigente calendario venatorio regionale, la specie in oggetto non \u00e8 pi\u00f9 cacciabile (periodo consentito solo dal 1 ottobre al 31 dicembre 2018) e di conseguenza l\u2019abbattimento costituisce un illecito di tipo penale; pertanto, con il coordinamento del Pubblico Ministero di turno presso la Procura della Repubblica di Castrovillari, sono state effettuate diverse perquisizioni volte a ricercare selvaggina protetta occultata.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-275680  aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/01\/Polizia-Provinciale.jpg\" alt=\"\" width=\"557\" height=\"371\" title=\"\"><br \/>\nIn un altro intervento condotto sempre dagli Agenti del distaccamento di San Giovanni in Fiore e finalizzato al contrasto del <strong>bracconaggio al cinghiale<\/strong>, specie per cui l\u2019attivit\u00e0 venatoria \u00e8 chiusa ormai dal 30 dicembre scorso, un uomo \u00e8 stato trovato con delle munizioni a palla unica portate e detenute illegalmente, poich\u00e9 non denunciate all\u2019autorit\u00e0 di pubblica sicurezza. Nel corso delle operazioni sono stati sequestrati complessivamente un fucile calibro 12, ventisette munizioni tra piombo spezzato e a palla asciutta, pi\u00f9 alcuni capi di avifauna illecitamente abbattuti; dopo le formalit\u00e0 di rito <strong>per i presunti responsabili \u00e8 scattata la denuncia<\/strong> in stato di libert\u00e0 alla competente Autorit\u00e0 giudiziaria, che ha gi\u00e0 convalidato l\u2019attivit\u00e0 della polizia giudiziaria operante. I controlli della Polizia Provinciale di Cosenza, tesi a garantire il corretto svolgimento dell\u2019attivit\u00e0 venatoria, la difesa del patrimonio faunistico, e la tutela della sicurezza pubblica, sono stati intensificati in questi ultimi periodi e proseguiranno anche nei prossimi giorni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vasta operazione della Polizia Provinciale \u00e8 stata messa in campo nell&#8217;ambito di una mirata attivit\u00e0 di prevenzione e repressione dei reati in materia venatoria<\/p>\n","protected":false},"author":42,"featured_media":105056,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-105055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105055"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105056"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}