{"id":10509,"date":"2012-12-28T17:07:05","date_gmt":"2012-12-28T16:07:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=10509"},"modified":"2023-01-17T13:43:37","modified_gmt":"2023-01-17T12:43:37","slug":"4742-approvato-documento-tecnico-allegato-al-bilancio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4742-approvato-documento-tecnico-allegato-al-bilancio\/","title":{"rendered":"Approvato documento tecnico allegato al bilancio"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>REGGIO CALABRIA<\/strong> &#8211; La Giunta regionale si \u00e8 riunita a Reggio Calabria sotto la presidenza del Presidente&nbsp;Giuseppe Scopelliti, con l\u2019assistenza del Dirigente<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">generale Francesco Zoccali.&nbsp;E\u2019 stato approvato, su proposta dell\u2019assessore Giacomo Mancini, il documento&nbsp;tecnico allegato al bilancio. Si \u00e8 quindi concluso l\u2019iter procedurale.&nbsp;Il sottosegretario Sarra ha informato la Giunta che il prossimo luned\u00ec sar\u00e0 trasmesso&nbsp;in Consiglio regionale, presso le apposite commissioni consiliari, il piano riforme gi\u00e0&nbsp;approvato dalla Giunta.&nbsp;Su proposta dell\u2019assessore al personale Domenico Tallini \u00e8 stato licenziato il piano&nbsp;di formazione del personale della Giunta, che prevede un accordo con la Scuola&nbsp;Superiore della Pubblica Amministrazione&nbsp;Approvato inoltre l\u2019aggiornamento del piano dei conti della contabilit\u00e0 generale delle&nbsp;aziende del s.s.r.&nbsp;Su proposta del Presidente Scopelliti la Giunta ha deliberato l&#8217;istituzione di un conto&nbsp;corrente bancario e postale regionale per la raccolta fondi solidale in favore della&nbsp;popolazione del Pollino e richiesta al dipartimento della protezione civile di avvio di&nbsp;procedura per raccolta fondi telefonica solidale. m.c.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; La Giunta regionale si \u00e8 riunita a Reggio Calabria sotto la presidenza del Presidente&nbsp;Giuseppe Scopelliti, con l\u2019assistenza del Dirigente<\/p>\n","protected":false},"author":22,"featured_media":10510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-10509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=10509"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/10510"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=10509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=10509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=10509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}