{"id":10511,"date":"2012-12-28T17:13:47","date_gmt":"2012-12-28T16:13:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=10511"},"modified":"2023-01-17T13:43:37","modified_gmt":"2023-01-17T12:43:37","slug":"4743-occhiuto-si-schiera-con-i-lavoratori-del-totobit","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4743-occhiuto-si-schiera-con-i-lavoratori-del-totobit\/","title":{"rendered":"Occhiuto si schiera con i lavoratori del Totobit"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> La <strong>Lottomatica<\/strong>&nbsp;&#8220;punta&#8221; sui lavoratori. S\u00ec, quelli da licenziare. Il sindaco <strong>Mario Occhiuto<\/strong> \u00e8 solidale con gli operatori e le operatrici<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">del <strong>Gruppo Lottomatica<\/strong> che avrebbe deciso di smantellare, entro il prossimo 31 dicembre, il suo <strong>laboratorio di Ricerca e sviluppo<\/strong> nel cosentino. \u201cSchierarsi a favore della salvaguardia del lavoro in Calabria \u00e8 un dovere a cui ognuno di noi, nei rispettivi ruoli, \u00e8 chiamato a rispondere. E\u2019 per questo che auspico una risoluzione positiva nella vicenda che coinvolge i dipendenti Totobit\u201d. Informato direttamente dai lavoratori Totobit, il primo cittadino ha immediatamente espresso la propria solidariet\u00e0 per una situazione che certamente arrecherebbe un danno al tessuto economico della citt\u00e0, oltre che un peggioramento dello status sociale di quanti si vedrebbero sradicati da questa regione e catapultati in un contesto metropolitano non facile come quello romano. Nello scorso mese di settembre, infatti, il capo del personale di Lottomatica ha comunicato ai dipendenti <strong>Totobit<\/strong> la scelta di trasferire il personale a Roma per accorparlo alla sede centrale. \u201cSe questa decisione dovesse essere confermata \u2013 aggiunge Occhiuto \u2013 le famiglie calabresi che traggono sostentamento da quest\u2019azienda subirebbero notevoli disagi. Mi auguro che i vertici della Lottomatica cambino saggiamente indirizzo, continuando a investire sulle nostre risorse umane qui sul territorio\u201d.<strong> Totobit Informatica \u00e8 l\u2019azienda del gruppo Lottomatica che gestisce servizi come: ricariche telefoniche, pagamento utenze, ecc. per oltre 130.000 punti vendita della Rete LIS (Lottomatica Italia Servizi) i quali eseguono giornalmente circa 1,5 milioni di transazioni finanziarie, l\u2019emissione dei tagliandi valori bollati per conto dell\u2019Agenzia delle Entrate movimentando circa 10 milioni di euro al giorno, l\u2019erogazione dei servizi CartaLIS IMEL (in collaborazione con Banca Sella) e la convalida delle vincite dei biglietti Gratta&amp;Vinci.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La Lottomatica&nbsp;&#8220;punta&#8221; sui lavoratori. S\u00ec, quelli da licenziare. Il sindaco Mario Occhiuto \u00e8 solidale con gli operatori e le operatrici<\/p>\n","protected":false},"author":22,"featured_media":10512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-10511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=10511"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/10511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/10512"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=10511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=10511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=10511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}