{"id":105113,"date":"2019-02-01T05:32:17","date_gmt":"2019-02-01T04:32:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/inquinamento-dellacqua-63-denunce-anche-in-calabria\/"},"modified":"2023-01-16T18:22:13","modified_gmt":"2023-01-16T17:22:13","slug":"275872-inquinamento-dellacqua-63-denunce-anche-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/275872-inquinamento-dellacqua-63-denunce-anche-in-calabria\/","title":{"rendered":"Inquinamento dell&#8217;acqua, 63 denunce. Anche in Calabria"},"content":{"rendered":"<h4>I militari che si occupano di tutela ambientale hanno raccolto soprattutto le segnalazioni di cittadini allarmati dai rischi di contaminazione delle falde<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Sono 63 le persone denunciate al termine di una vasta operazione dei Carabinieri del Comando per la Tutela ambientale finalizzata al contrasto all&#8217;inquinamento idrico con particolare riferimento ai processi di depurazione delle acque reflue industriali. I controlli e le indagini hanno interessato per diverse settimane le regioni Campania, <strong>Calabria<\/strong>, Basilicata e Puglia.<\/p>\n<p>I denunciati all&#8217;autorit\u00e0 giudiziaria sono titolari, amministratori e gestori di aziende responsabili di inosservanza o assenza delle previste autorizzazioni agli scarichi di tipo industriale, violazione prevista dal Codice dell&#8217;Ambiente, per la quale si prevede l&#8217;arresto da due mesi a due anni o l&#8217;ammenda da millecinquecento a diecimila euro. Raccogliendo soprattutto le segnalazioni di cittadini allarmati dai rischi di contaminazione delle falde, sotto la lente d&#8217;ingrandimento dei Carabinieri sono finite <strong>aziende attive nei settori delle materie plastiche, chimiche, di produzione di materiale ferroso, officine meccaniche, autolavaggi nonch\u00e9 alberghi e plessi ospedalieri pubblici o privati.<\/strong><\/p>\n<p>I controlli, riferiscono i militari, hanno consentito di accertare sversamenti illegali, spesso di sostanze altamente inquinanti e tossiche nelle fognature pubbliche, in canali di scolo o nei casi pi\u00f9 gravi in mare, fiumi o torrenti.<strong> I sequestri hanno superato i 5 milioni di euro<\/strong> e riguardato condotte di scarico, vasche di deposito reflui, pozzi, ma anche interi impianti di produzione ed aziende, di cui \u00e8 stata sospesa temporaneamente l&#8217;attivit\u00e0. Analoghi controlli verranno ripetuti nei prossimi mesi anche in altre Regioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I militari che si occupano di tutela ambientale hanno raccolto soprattutto le segnalazioni di cittadini allarmati dai rischi di contaminazione delle falde<\/p>\n","protected":false},"author":42,"featured_media":105114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[],"class_list":["post-105113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105113"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105114"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}