{"id":105216,"date":"2019-02-03T17:37:11","date_gmt":"2019-02-03T16:37:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/derby-reggina-catanzaro-finisce-con-una-sassaiola\/"},"modified":"2023-01-16T18:22:20","modified_gmt":"2023-01-16T17:22:20","slug":"276208-derby-reggina-catanzaro-finisce-con-una-sassaiola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/276208-derby-reggina-catanzaro-finisce-con-una-sassaiola\/","title":{"rendered":"Derby Reggina &#8211; Catanzaro finisce con una sassaiola"},"content":{"rendered":"<h4>I bus dei tifosi del Catanzaro hanno lasciato la citt\u00e0 mentre venivano raggiunti da una raffica di pietre lanciate da ignoti<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; Quattro pullman di tifosi del Catanzaro, dopo avere lasciato da pochi minuti lo stadio Granillo di Reggio Calabria, a conclusione del derby Reggina-Catanzaro di serie C, finito 4-3 a favore degli ospiti, sono stati fatti bersaglio di una sassaiola da parte di ignoti. Il fatto \u00e8 accaduto all&#8217;altezza del Ponte San Pietro della citt\u00e0 dello Stretto, sulla <strong>bretella di raccordo con l&#8217;A2 Autostrada del Mediterraneo.<\/strong> I tifosi catanzaresi, accompagnati da una forte scorta di carabinieri e polizia, avevano da pochi minuti lasciato lo stadio per fare rientro a Catanzaro. Secondo quanto riferito dalle forze dell&#8217;ordine i pullman dei tifosi catanzaresi hanno comunque proseguito regolarmente verso il capoluogo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I bus dei tifosi del Catanzaro hanno lasciato la citt\u00e0 mentre venivano raggiunti da una raffica di pietre lanciate da ignoti<\/p>\n","protected":false},"author":43,"featured_media":105217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-105216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105216"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105217"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}