{"id":105476,"date":"2019-02-10T08:50:14","date_gmt":"2019-02-10T07:50:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-sgombero-per-il-tennis-clu-si-mortifica-lo-sport\/"},"modified":"2023-01-16T18:22:37","modified_gmt":"2023-01-16T17:22:37","slug":"277128-rende-sgombero-per-il-tennis-clu-si-mortifica-lo-sport","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/277128-rende-sgombero-per-il-tennis-clu-si-mortifica-lo-sport\/","title":{"rendered":"Rende, sgombero per &#8220;Il Tennis Club&#8221;: &#8220;Si mortifica lo sport&#8221;"},"content":{"rendered":"<h4>Per Tenuta del Psi l&#8217;ordinanza emessa dal Comune di Rende\u00a0ha una matrice solo ed esclusivamente politica<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; \u00abL\u2019ordinanza n\u00b0 14 del 2019 di sgombero dell\u2019impianto sportivo di Commenda, indirizzata, pochi giorni fa, all\u2019associazione Tennis Club Rende, mortifica lo sport della citt\u00e0 di Rende; mortifica tutta la disciplina tennistica; mortifica una importante storia che ha da sempre costituito un\u2019eccellenza sportiva della provincia di Cosenza e dell\u2019intero Sud Italia\u00bb. A dirlo Francesco Tenuta\u00a0 segretario Psi Rende<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_258845\" style=\"width: 315px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-258845\" class=\"wp-image-258845 size-medium\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/avvocato-Tenuta-305x280.jpg\" alt=\"\" width=\"305\" height=\"280\" title=\"\"><p id=\"caption-attachment-258845\" class=\"wp-caption-text\">Il segretario Psi Francesco Tenuta<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>\u00abL\u2019emissione di tale provvedimento \u00e8 risultata oltremodo inopportuna, se si considera che il merito della vicenda relativa alla illegittimit\u00e0 o meno del bando di Project Financing, messo in piedi dall\u2019attuale amministrazione, sar\u00e0 discusso il prossimo mese di maggio davanti al TAR Calabria; e, certamente, assai dannosa per le casse comunali, se si considera che il Comune si dovr\u00e0 fare carico delle spese relative ai servizi di custodia e di guardiania dell\u2019intero impianto sportivo.<\/p>\n<p>\u00c8 inutile ribadire, ancora una volta, che la esclusione di tutte le associazione sportive dilettantistiche (Asd) e, dunque, dell\u2019associazione Tennis Club Rende, dalla gestione dell\u2019impianto sportivo di Commenda, cos\u00ec per come indicato nel bando, in uno alla predetta ordinanza di sgombero, hanno una matrice solo ed esclusivamente politica. E\u00a0 cos\u00ec, evidentemente, non pu\u00f2 essere.<\/p>\n<p>Non \u00e8 un caso che, subito dopo la vittoria delle comunali del 2014, l\u2019attuale amministrazione non abbia concesso al Tennis Club il campo di calcetto realizzato dalla Provincia di Cosenza, cos\u00ec per come previsto dalla delibera n\u00b0 51\/2009 di assegnazione dell\u2019impianto; non \u00e8 un caso, ancora, che l\u2019amministrazione Manna sia ricorsa, negli anni, agli affidamenti diretti o alle proroghe delle concessioni sportive nei confronti di altre associazioni sportive ( come la Rende Nuoto, il Rende Calcio, lo Sporting Club Arcavacata, il Club Saporito), tranne che per il Tennis Club.<\/p>\n<p>Guarda caso, soltanto per quest\u2019ultima, ci si \u00e8 affrettati a creare un bando ad hoc per estrometterla dalla gestione dell\u2019impianto, nonostante la stessa associazione avesse richiesto, in data 25.6.2018, una ulteriore proroga di affidamento con annesso progetto di miglioramento della struttura sportiva comunale di circa un milione di euro; nonostante la stessa associazione avesse gi\u00e0 realizzato, a proprie spese, una parte della struttura e avesse gi\u00e0 contribuito, anche attraverso cospicui investimenti, a mantenere l\u2019impianto nelle condizioni pi\u00f9 efficienti per offrire alla citt\u00e0 una adeguata offerta sportiva senza precedenti.<\/p>\n<p>Chi c\u2019\u00e8 dietro la nuova societ\u00e0 che ha presentato il progetto di finanza e quali interessi ci sono?\u00a0\u00a0Chi sono gli amministratori che si sono affannati\u00a0\u00a0negli ultimi anni a costituire nuove societ\u00e0 per la gestione dell\u2019impianto?Auspichiamo che l\u2019amministrazione possa prorogare la concessione dell\u2019impianto sportivo all\u2019associazione Tennis Club Rende, almeno fino a quando non sar\u00e0 risolta, da un punto di vista strettamente giuridico, il merito di questa annosa vicenda\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per Tenuta del Psi l&#8217;ordinanza emessa dal Comune di Rende\u00a0ha una matrice solo ed esclusivamente politica<\/p>\n","protected":false},"author":44,"featured_media":105477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-105476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105476"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105477"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}