{"id":105478,"date":"2019-02-10T10:25:13","date_gmt":"2019-02-10T09:25:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/consiglio-distrettuale-di-disciplina-locco-eletto-presidente\/"},"modified":"2023-01-16T18:22:37","modified_gmt":"2023-01-16T17:22:37","slug":"277130-consiglio-distrettuale-di-disciplina-locco-eletto-presidente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/277130-consiglio-distrettuale-di-disciplina-locco-eletto-presidente\/","title":{"rendered":"Consiglio distrettuale di disciplina: Locco eletto presidente"},"content":{"rendered":"<h4>L&#8217;avvocato Franco Locco \u00e8 stato eletto presidente del Consiglio Distrettuale di Disciplina (CDD) il nuovo organismo che ha il compito del controllo disciplinare sugli avvocati iscritti all\u2019albo<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Una nomina importante quella dell&#8217;avvocato del foro di Cosenza, <strong>Franco Locco, letto Presidente del\u00a0<\/strong><strong>Consiglio distrettuale di disciplina<\/strong> presso la Corte di appello di Catanzaro. L&#8217;Organismo, con la nuova legge professionale forense, ha la competenza <strong>disciplinare sugli avvocati di tutti i 7 ordini del Distretto<\/strong>. Gli Ordini professionali forensi non possono pi\u00f9 giudicare sui procedimenti disciplinari aperti nei confronti degli avvocati, la competenza spetta dal 2015 ad un <strong>organismo autonomo ed indipendente che ha sede a Catanzaro.<\/strong><\/p>\n<p>L&#8217;organismo garantisce che l&#8217;Avvocatura svolga nella societ\u00e0 con credibilit\u00e0 il ruolo essenziale e insostituibile che le compete, tutelando\u00a0il rischio sempre pi\u00f9 concreto di recare discredito alla figura ed al ruolo dell\u2019avvocato. Una svolta decisiva in questa direzione, che pone al riparo il procedimento da ogni intromissione di soggetti esterni.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-277131 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/aula_di_giustizia-jpg-653x367-440x247.jpg\" alt=\"\" width=\"440\" height=\"247\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Il CDD valuta una notizia di illecito disciplinare e avvia la fase istruttoria nei confronti dell&#8217;avvocato; deve provvedere ad ogni accertamento istruttorio per poi presentare alla Sezione le sue richieste: di archiviazione o di approvazione del capo di incolpazione all\u2019esito della fase istruttoria preliminare, di archiviazione o di citazione a giudizio alla conclusione della fase istruttoria.\u00a0La legge ha quindi dotato l\u2019Avvocatura degli strumenti idonei e necessari rimettendole un potere regolamentare pieno ed incondizionato.<\/p>\n<div id=\"attachment_277134\" style=\"width: 205px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-277134\" class=\"wp-image-277134 size-medium\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/b759799e-53ae-439b-b85f-332ebb06af11-1-195x280.jpg\" alt=\"\" width=\"195\" height=\"280\" title=\"\"><p id=\"caption-attachment-277134\" class=\"wp-caption-text\">L&#8217;avvocato Franco Locco presidente del Consiglio Distrettuale di Disciplina<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Nella giornata di ieri dopo le elezioni dei 31 componenti che erano avvenute nei mesi scorsi, si \u00e8 insediato a Catanzaro, il Consiglio di disciplina degli avvocati che ha proceduto alla <strong>elezione del suo presidente<\/strong>, <strong>designando nel delicato e autorevole compito l&#8217;avvocato Franco Locco<\/strong>.<\/p>\n<p>Al neo presidente Locco gli auguri per l&#8217;importante carica assunta dalla redazione di Qui Cosenza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;avvocato Franco Locco \u00e8 stato eletto presidente del Consiglio Distrettuale di Disciplina (CDD) il nuovo organismo che ha il compito del controllo disciplinare sugli avvocati iscritti all\u2019albo<\/p>\n","protected":false},"author":40,"featured_media":105479,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42],"tags":[],"class_list":["post-105478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105478"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105479"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}