{"id":105484,"date":"2019-02-10T16:06:09","date_gmt":"2019-02-10T15:06:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-fiera-di-san-giuseppe-2019-scelta-la-location\/"},"modified":"2023-01-16T18:22:38","modified_gmt":"2023-01-16T17:22:38","slug":"277172-cosenza-fiera-di-san-giuseppe-2019-scelta-la-location","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/277172-cosenza-fiera-di-san-giuseppe-2019-scelta-la-location\/","title":{"rendered":"Cosenza, fiera di San Giuseppe 2019: scelta la location"},"content":{"rendered":"<h4><strong>Location confermata su viale Mancini e novit\u00e0 in arrivo. Domani l\u2019assessore Pastore in Commissione Attivit\u00e0 Produttive<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Proseguono i preparativi organizzativi in vista dell\u2019edizione 2019 della tradizionale fiera di San Giuseppe. La location prescelta dall\u2019assessorato alle Attivit\u00e0 Economiche e produttive, di concerto con gli altri uffici comunali interessati, \u00e8 viale Mancini. Una scelta naturale non solo per gli ottimi riscontri degli anni scorsi, ma per certi aspetti resa anche obbligata dalle sempre pi\u00f9 stringenti norme in materia di sicurezza che regolano le manifestazioni pubbliche. Le esperienze passate hanno infatti dimostrato che il viale si presta ad ospitare l\u2019evento garantendo fruibilit\u00e0 e accessibilit\u00e0 a tutti, nonch\u00e9 la possibilit\u00e0 di organizzare al meglio i servizi accessori e la sicurezza per espositori e visitatori.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_138860\" style=\"width: 338px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-138860\" class=\"wp-image-138860 size-medium\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/02\/Loredana-Pastore-328x280.jpg\" alt=\"\" width=\"328\" height=\"280\" title=\"\"><p id=\"caption-attachment-138860\" class=\"wp-caption-text\">L&#8217;assessore Loredana Pastore<\/p><\/div>\n<p>\u201cAlcuni dettagli della manifestazione non sono stati ancora del tutto definiti \u2013 spiega al riguardo l\u2019assessore alle Attivit\u00e0 Economiche e Produttive Loredana Pastore &#8211; Nei giorni scorsi abbiamo pubblicato una manifestazione d\u2019interesse per ospitare all\u2019interno della fiera le eccellenze artigiane del territorio che renderanno questa edizione ancora pi\u00f9 suggestiva e attrattiva\u201d.<\/p>\n<p>Luned\u00ec 11 febbraio l\u2019assessore Pastore insieme alla dirigente al ramo, Angela Carbone, incontrer\u00e0 i componenti della commissione Attivit\u00e0 Produttive proprio per dibattere in merito alle iniziative in corso e per puntellare ulteriori elementi, mentre nel frattempo, come ogni anno in questo periodo, cresce l\u2019attesa per una manifestazione che \u00e8 indiscutibilmente patrimonio identitario della citt\u00e0 di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Location confermata su viale Mancini e novit\u00e0 in arrivo. Domani l\u2019assessore Pastore in Commissione Attivit\u00e0 Produttive<\/p>\n","protected":false},"author":44,"featured_media":105485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-105484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105484"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}