{"id":105525,"date":"2019-02-11T17:49:44","date_gmt":"2019-02-11T16:49:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/in-sei-denunciati-per-porto-abusivo-darma-in-luogo-pubblico\/"},"modified":"2023-01-16T18:22:41","modified_gmt":"2023-01-16T17:22:41","slug":"277335-in-sei-denunciati-per-porto-abusivo-darma-in-luogo-pubblico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/277335-in-sei-denunciati-per-porto-abusivo-darma-in-luogo-pubblico\/","title":{"rendered":"In sei denunciati per porto abusivo d&#8217;arma in luogo pubblico"},"content":{"rendered":"<h4>&#8220;Cacciatori&#8221; senza permesso venatorio, un fucile calibro 12,\u00a0coltelli a serramanico e di una tessera tascabile che, una volta aperta, diveniva un coltello di 9 cm<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TAURIANOVA (RC) &#8211; Lo scorso fine settimana, i Carabinieri della Compagnia di Taurianova hanno svolto un servizio straordinario di controllo del territorio a Cittanova e Taurianova finalizzato alla prevenzione e repressione dei reati predatori, dei delitti in materia armi e delle condotte di guida in stato di alterazione psicofisica, che ha portato ad un arresto in flagranza di reato e al deferimento all\u2019Autorit\u00e0 Giudiziaria di 6 persone, per i reati di porto abusivo di arma da sparo in luogo pubblico, di porto abusivo di armi bianche e di guida in stato di ebbrezza.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-277340 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/Foto-1-278x280.jpg\" alt=\"\" width=\"278\" height=\"280\" title=\"\"><\/p>\n<p>In particolare, i Carabinieri della Stazione di Cittanova, hanno sorpreso Longo Francesco, 63enne di Cittanova, a praticare l\u2019attivit\u00e0 venatoria in Contrada San Leone di Cittanova, sparando diversi colpi con un fucile cal. 12. Pi\u00f9 approfondite verifiche hanno consentito di accertare che l\u2019uomo, bench\u00e9 avesse l\u2019arma legalmente denunciata, non aveva nessun autorizzazione ad esercitare l\u2019attivit\u00e0 venatoria. Il Longo \u00e8 stato quindi tratto in arresto in flagranza per il reato di porto abusivo di armi comune di sparo in luogo pubblico e messo a disposizione dell\u2019A.G..<\/p>\n<p>Nel corso del servizio inoltre, un uomo P.G., 62 enne di Taurianova e un giovane G.G., ventenne di Rizziconi, durante i controlli stradali sono stati fermati in auto in evidente stato di alterazione e, sottoposti ai previsti accertamenti, sono risultati positivi all\u2019alcoltest. Entrambi sono stati deferiti all\u2019Autorit\u00e0 Giudiziaria per il reato di guida in stato di ebbrezza e li sono state ritirare le patenti di guida. Nella rete dei controlli sono finiti anche altre 4 persone, T.P., 36 enne di Plati, T.P., 41enne di Plat\u00ec, T.N. 20enne di Plat\u00ec, nonch\u00e9 T.M., 39enne di Varapodio, tutti gi\u00e0 gravati da precedenti di polizia, i quali, fermati e sottoposti a perquisizione in distinte occasioni, sono stati trovati in possesso di coltelli a serramanico e di una tessera tascabile che, una volta aperta, diveniva un coltello di 9 cm.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-277342 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/Foto-3-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p>Nel corso del servizio straordinario sono stati controllati complessivamente 82 persone e 48 mezzi, ed ispezionati nr. 3 locali pubblici.<br \/>\nTale servizio rientra nella pi\u00f9 ampia azione di contrasto dei Carabinieri della Compagnia di Taurianova contro i reati predatori nel territorio, il porto di armi o oggetti atti ad offendere e la prevenzione e repressione delle condotte di guida in stato di alterazione psicofisica dei giovani, soprattutto nel fine settimana, nonch\u00e9 ai fenomeni di microcriminalit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-277341 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/Foto-2-420x280.jpg\" alt=\"\" width=\"420\" height=\"280\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Cacciatori&#8221; senza permesso venatorio, un fucile calibro 12,\u00a0coltelli a serramanico e di una tessera tascabile che, una volta aperta, diveniva un coltello di 9 cm<\/p>\n","protected":false},"author":44,"featured_media":105526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105525"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105526"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}