{"id":105593,"date":"2019-02-13T07:23:34","date_gmt":"2019-02-13T06:23:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/meteo-cosenza-vento-gelido-e-spruzzate-di-neve-anche-a-quote-basse\/"},"modified":"2023-01-16T18:22:45","modified_gmt":"2023-01-16T17:22:45","slug":"277570-meteo-cosenza-vento-gelido-e-spruzzate-di-neve-anche-a-quote-basse","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/277570-meteo-cosenza-vento-gelido-e-spruzzate-di-neve-anche-a-quote-basse\/","title":{"rendered":"Meteo Cosenza, vento gelido e spruzzate di neve anche a quote basse"},"content":{"rendered":"<h4>L&#8217;aria fredda proveniente dai Balcani ha fatto crollare le temperature anche di 10 gradi. Bufere di neve in Sila e fiocchi anche a quote basse nella notte per effetto dei forti venti di tramontana\u00a0<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Una<strong> discesa di aria fredda<\/strong>, lungo il bordo orientale dell&#8217;Anticiclone, sta interessando le regioni centrali e quelle del sud Italia, Calabria compresa. L&#8217;aria fredda in arrivo da est ha determinato un<strong> brusco calo delle temperature<\/strong>, acuito ancora di pi\u00f9 dai <strong>forti venti di tramontana<\/strong> che spirano dalla notte con raffiche davvero intense sopratutto sulla parte settentrionale e jonica della nostra regione. Aria fredda che mantiene anche una certa instabilit\u00e0 soprattutto sui versanti orientali di Sila e Pollino dove l<strong>a neve \u00e8 caduta nella notte con vere e proprie bufere<\/strong>. I fiocchi in mattinata si sono spinti sulla fascia presilana e pi\u00f9 gi\u00f9 anche a quote relativamente basse (400-500 metri).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-128853\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2016\/12\/Neve-Camilgiatello-2.jpg\" alt=\"\" width=\"582\" height=\"310\" title=\"\"><\/p>\n<p><strong>Qualche fiocco coreografico spinto dal <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5979\" target=\"_blank\" rel=\"noopener\">vento<\/a> <\/span>si \u00e8 visto anche a Cosenza,\u00a0<\/strong>ma dal punto di vista delle precipitazioni il tempo destinato comunque a migliorare rapidamente gi\u00e0 dalla mattinata, anche se fino a domani saranno <strong>possibili ancora rovesci sparsi a carattere nevoso<\/strong> a quote relativamente basse in un contesto ancora <strong>ventoso e freddo<\/strong>. Nel proseguo della settimana ci saranno poche novit\u00e0, con l&#8217;anticiclone che continuer\u00e0 a garantire bel tempo su buona parte del Mediterraneo, mente il sud sar\u00e0 ancora alle prese con infiltrazioni di aria pi\u00f9 fredda da est.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;aria fredda proveniente dai Balcani ha fatto crollare le temperature anche di 10 gradi. Bufere di neve in Sila e fiocchi anche a quote basse nella notte per effetto dei forti venti di tramontana\u00a0<\/p>\n","protected":false},"author":22,"featured_media":105594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[539],"class_list":["post-105593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-neve"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105593"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105594"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}