{"id":105765,"date":"2019-02-17T18:07:42","date_gmt":"2019-02-17T17:07:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-e-un-tunnel-senza-fine-biancorossi-nuovamente-ko-con-un-goal-al-94\/"},"modified":"2023-01-16T18:22:57","modified_gmt":"2023-01-16T17:22:57","slug":"278215-rende-e-un-tunnel-senza-fine-biancorossi-nuovamente-ko-con-un-goal-al-94","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278215-rende-e-un-tunnel-senza-fine-biancorossi-nuovamente-ko-con-un-goal-al-94\/","title":{"rendered":"Rende, \u00e8 un tunnel senza fine. Biancorossi nuovamente ko con un goal al 94&#8242;"},"content":{"rendered":"<h4>Non basta l&#8217;iniziale vantaggio di Goretta su calcio di rigore. Il Bisceglie pareggia con una magistrale punizione di Triarico e trova il goal vittoria in pieno recupero con il colpo al volo di Risolo che manda in delirio i pugliesi<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>BISCEGLIE (BA) &#8211; Niente da fare, il Rende non riesce a scrollarsi di dosso il periodo nerissimo e <strong>colleziona una nuova sconfitta<\/strong>\u00a0(la settima in 8 gare) che continua a fare male ad una classifica sempre pi\u00f9 deficitaria e malissimo al morale di una squadra che nonostante <strong>l&#8217;iniziale vantaggio siglato da Goretta su calcio di rigore in apertura di secondo tempo<\/strong>\u00a0(fallo netto di Maestrelli su Cipolla) ha subito <strong>la rimonta di un Bisceglie volitivo e determinato<\/strong> che prima\u00a0<strong>pareggia al 50&#8242; con un calcio di punizione che Triarico pennellato all&#8217;incrocio dei pali<\/strong>, poi trova il <strong>goal vittoria proprio all&#8217;ultimo assalto <\/strong>ritrovando il successo dopo due mesi di astinenza. Il cronometro segna 94 minuti quando su un fallo laterale scodellato in area di rigore da Giron, Statira prolunga di testa la sfera che finisce sul destro di Risolo appostato all&#8217;altezza del dischetto. <strong>Il tiro, forse deviato, si spegne nell&#8217;angolo basso alla destra di Borsellino<\/strong>. Disperazione tra i giocatori biancorossi mentre lo stadio Ventura \u00e8 una bolgia con i pugliesi che portano a casa tre punti di enorme importanza in ottica salvezza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-278248\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/BISCEGLIE-RENDE2.jpg\" alt=\"\" width=\"591\" height=\"329\" title=\"\"><\/p>\n<p>Il primo tempo era passato via tutto sommato senza grossi sussulti anche se le migliori occasioni sono tutte dei padrini di casa che hanno comunque provato a menare le danze con il Rende pronto a colpire in contropiede. <strong>Al 17&#8242; Borsellino vola a deviare un colpo di testa di Starita,<\/strong> bravo a incornare un preciso cross di Giron. Sul susseguente calcio d&#8217;angolo l<strong>o stesso attaccante napoletano, appostato sul secondo palo, spara sull&#8217;esterno della rete<\/strong> da ottima posizione. Poco dopo la mezzora ancora<strong> Starita gira al volo un assist di tacco di Jovanovic<\/strong> con la palla che esce di poco sul fondo. Come detto <strong>la ripresa si apre con il vantaggio dei biancorossi su calcio di rigore trasformato da Goretta<\/strong>. Nemmeno il tempo di festeggiare e <strong>Triarico toglie dal cilindro una punizione alla Del Piero<\/strong>\u00a0mandando il pallone a morire proprio nel sette.\u00a0 Ma dopo i fuochi d&#8217;artificio iniziali il secondo tempo scorre senza grosse emozioni con le due squadre che lottano in tutte le zone del campo ma creano pochissimo. Il Bisceglie per\u00f2 ha forse il merito di crederci di pi\u00f9 e dopo aver sfiorato il vantaggio con un c<strong>olpo di testa di Scalzone al 90&#8242; che esce di un nulla<\/strong>, trova il goal vittoria al 94&#8242; con il colpo al volo di Risolo.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p style=\"font-weight: 400;\"><strong>BISCEGLIE (3-5-2):<\/strong> Cerofolini; Markic, Maccarrone, Maestrelli; Longo (78&#8242; Scalzone), Risolo, Bangu, Triarico, Giron; Starita, Jovanovic\u00a0(62&#8242; Cuppone)<br \/>\n<strong>Panchina:<\/strong> Bottalico, Camporeale,Casella, Cuomo D, Cuppone, Dellino, Djoulou, Mastrilli, Mosti, Ndiae, Scalzone, Vassallo.<br \/>\n<strong>Allenatore:<\/strong> Rodolfo Vanoli<\/p>\n<p style=\"font-weight: 400;\"><strong>RENDE (3-4-3):<\/strong> Borsellini; Minelli, Maddaloni, Sabato; Viteritti\u00a0(76&#8242; Blaze), Cipolla (49&#8242; Rossini), Franco, Giannotti; Borello\u00a0(71&#8242; Boretto), Brignoli\u00a0(76&#8242; Laaribi); Actis Goretta<br \/>\n<strong>Panchina:<\/strong> Palermo, Awua, Bei, Blaze, Bonetto, Laaribi, Leveque, Rossini<br \/>\n<strong>Allenatore:<\/strong> Francesco Modesto<\/p>\n<p style=\"font-weight: 400;\"><strong>Arbitro:<\/strong> Signor Davide Moriconi di Roma 2<br \/>\n<strong>Assistenti<\/strong>: Signor Amir Salama di Ostia Lido e signor Domenico Fontemurato di Roma 2<\/p>\n<p><strong>Ammoniti:\u00a0<\/strong>Brignoli\u00a0(R), Risolo (B)<\/p>\n<p><strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli:<\/strong> 9-5<\/p>\n<p><strong>Recupero:<\/strong> 1&#8242; p.t &#8211; 4&#8242; s.t.<\/p>\n<p><strong>Note: <\/strong>Pomeriggio gradevole e soleggiato a Bisceglie con una temperatura vicina ai 14 gradi. Terreno del Ventura in discrete condizioni. Presenti poco pi\u00f9 di 500 spettatori con una decina di tifosi del Rende<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non basta l&#8217;iniziale vantaggio di Goretta su calcio di rigore. Il Bisceglie pareggia con una magistrale punizione di Triarico e trova il goal vittoria in pieno recupero con il colpo al volo di Risolo che manda in delirio i pugliesi<\/p>\n","protected":false},"author":24,"featured_media":105766,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-105765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105765"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105765\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105766"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}