{"id":105782,"date":"2019-02-18T11:41:55","date_gmt":"2019-02-18T10:41:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendio-abitazioni-ustionata-la-proprietaria\/"},"modified":"2023-01-16T18:22:58","modified_gmt":"2023-01-16T17:22:58","slug":"278294-incendio-abitazioni-ustionata-la-proprietaria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278294-incendio-abitazioni-ustionata-la-proprietaria\/","title":{"rendered":"Incendio abitazioni, ustionata la proprietaria"},"content":{"rendered":"<h4>Squadra dei Vigili del Fuoco del distaccamento di Soverato \u00e8 intervenuta ieri sera in via Martin Luther King nel comune di Soverato per incendio all&#8217;interno di una abitazione<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SOVERATO (CZ) &#8211; Un probabile ritorno di fiamma dal camino ha innescato l&#8217;incendio che ha danneggiato parte dell&#8217;arredamento.<br \/>\nFerita la proprietaria dell&#8217;appartamento che trovandosi seduta sul divano nelle vicinanze del caminetto, veniva investita dalle fiamme riportando ustioni lievi alle braccia, al torace ed alle gambe.<br \/>\nLa stessa, veniva presa in cura dal personale sanitario del Suem118 e trasferita presso struttura ospedaliera.<br \/>\nIl tempestivo intervento dei soccorritori ha evitato il propagarsi delle fiamme all&#8217;intera abitazione.<br \/>\nIl fumo denso provocava altres\u00ec l&#8217;annerimento delle pareti del locale interessato dal rogo.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-278297\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-17-at-22.45.43-440x247.jpeg\" alt=\"\" width=\"440\" height=\"247\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-278296\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-17-at-22.45.34-374x280.jpeg\" alt=\"\" width=\"374\" height=\"280\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Squadra dei Vigili del Fuoco del distaccamento di Soverato \u00e8 intervenuta ieri sera in via Martin Luther King nel comune di Soverato per incendio all&#8217;interno di una abitazione<\/p>\n","protected":false},"author":44,"featured_media":105783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105782"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105783"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}