{"id":105788,"date":"2019-02-18T14:10:02","date_gmt":"2019-02-18T13:10:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendio-baraccopoli-trasferiti-altri-35-migranti\/"},"modified":"2023-01-16T18:22:58","modified_gmt":"2023-01-16T17:22:58","slug":"278304-incendio-baraccopoli-trasferiti-altri-35-migranti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278304-incendio-baraccopoli-trasferiti-altri-35-migranti\/","title":{"rendered":"Incendio baraccopoli: trasferiti altri 35 migranti"},"content":{"rendered":"<h4>Un nuovo incendio nella baraccopoli di San Ferdinando ha accelerato i trasferimenti dei migranti<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN FERDINANDO (RC) &#8211; Altri 35 migranti che abitavano nella baraccopoli di San Ferdinando hanno lasciato oggi il ghetto per trasferirsi in Cas della regione, a Isola Capo Rizzuto, Maierato e Reggio Calabria. Vanno ad aggiungersi ai 26 gi\u00e0 partiti tra sabato e domenica. Intanto, nella baraccopoli, la situazione \u00e8 tranquilla, dopo il rogo che nella notte tra venerd\u00ec e sabato ha provocato la morte di Moussa Ba, 29enne senegalese. Molti dei migranti che vivono nell&#8217;area sono ancora impegnati nei campi, anche se la stagione della raccolta degli agrumi \u00e8 ormai alla fine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo incendio nella baraccopoli di San Ferdinando ha accelerato i trasferimenti dei migranti<\/p>\n","protected":false},"author":44,"featured_media":105789,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105788"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105789"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}