{"id":105800,"date":"2019-02-18T15:24:12","date_gmt":"2019-02-18T14:24:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-sindaco-di-cosenza-tradisce-i-senzatetto-a-rischio-sgombero\/"},"modified":"2023-01-16T18:23:00","modified_gmt":"2023-01-16T17:23:00","slug":"278325-il-sindaco-di-cosenza-tradisce-i-senzatetto-a-rischio-sgombero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278325-il-sindaco-di-cosenza-tradisce-i-senzatetto-a-rischio-sgombero\/","title":{"rendered":"Il sindaco di Cosenza &#8216;tradisce&#8217; i senzatetto a rischio sgombero"},"content":{"rendered":"<h4>Il Comune di Cosenza ha bloccato la ricerca di alloggi per l&#8217;emergenza abitativa che il sindaco Mario Occhiuto aveva promesso di reperire per evitare che le decine di persone che vivono tra l&#8217;ex stabile Aterp di via Savoia e l&#8217;hotel Centrale finissero in strada<br \/>\n<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00abL\u2019 8 ottobre 2018, &#8211; ricorda in una nota il Comitato\u00a0Prendocasa Cosenza &#8211; a causa della pressante minaccia di sgombero delle occupazioni abitative e del conseguente silenzio degli enti locali, occupammo simbolicamente l\u2019ex Hotel Jolly, chiedendo e ottenendo un incontro in Prefettura. Al tavolo inter \u2013 istituzionale, presieduto dal prefetto Paola Galeone, parteciparono il sindaco Mario Occhiuto accompagnato dai dirigenti comunali, il commissario A.T.E.R.P Ambrogio Mascherpa e l\u2019assessore regionale Roberto Musmanno. Il primo cittadino propose come soluzione l\u2019utilizzo della cosiddetta misura di \u201cemergenza abitativa\u201d, in modo da<strong> rispondere al problema abitativo vissuto da centinaia di persone, evitando cos\u00ec gli sgomberi coatti dell\u2019Hotel Centrale e dello stabile di via Savoia.<\/strong> Pochi giorni dopo Palazzo dei Bruzi, con l\u2019avallo dei vertici della Prefettura, pubblic\u00f2 una manifestazione di interesse mirata alla ricerca di alloggi in fitto. In questi mesi ci siamo confrontati numerose volte con il dirigente comunale Giuseppe Nardi e i suoi collaboratori per dare seguito alla decisione emersa dal tavolo in Prefettura.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Negli ultimi giorni la situazione \u00e8 andata modificandosi, naufragando completamente.<strong> Il Comune ha, di fatto, bloccato la ricerca di alloggi, venendo meno alle promesse fatte dal sindaco Occhiuto in Prefettura.<\/strong> Dopo quattro mesi di parole, che a questo punto possiamo definire bugie, da parte di organi istituzionali negligenti e incapaci di gestire una questione cos\u00ec importante, ci troviamo al punto di partenza, con gli sgomberi nuovamente alle porte. A questo punto c\u2019\u00e8 da chiedersi: quali saranno le soluzioni in campo per far fronte alla situazione? Il prefetto e il sindaco sono pronti a far rivivere a questa citt\u00e0 il dramma di blitz polizieschi atti a \u201cbuttare\u201d uomini, donne e bambini fuori di casa senza soluzioni? E ancora, i rappresentanti del governo sul territorio, per primi i parlamentari del Movimento 5 Stelle, cos&#8217;hanno da dire di fronte ai paventati sgomberi? Noi non staremo a guardare, pronti a batterci fino alla fine per avere garantito il diritto a una casa e, quindi, a una vita degna\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">In foto l&#8217;occupazione simbolica dell&#8217;Hotel Jolly prima della demolizione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Cosenza ha bloccato la ricerca di alloggi per l&#8217;emergenza abitativa che il sindaco Mario Occhiuto aveva promesso di reperire per evitare che le decine di persone che vivono tra l&#8217;ex stabile Aterp di via Savoia e l&#8217;hotel Centrale finissero in strada<\/p>\n","protected":false},"author":43,"featured_media":105801,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-105800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105800"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105801"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}