{"id":105819,"date":"2019-02-18T17:20:05","date_gmt":"2019-02-18T16:20:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/autovelox-sulla-106-per-fare-cassa-la-procura-apre-uninchiesta\/"},"modified":"2023-01-16T18:23:00","modified_gmt":"2023-01-16T17:23:00","slug":"278398-autovelox-sulla-106-per-fare-cassa-la-procura-apre-uninchiesta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278398-autovelox-sulla-106-per-fare-cassa-la-procura-apre-uninchiesta\/","title":{"rendered":"Autovelox sulla 106 per fare cassa? La Procura apre un&#8217;inchiesta"},"content":{"rendered":"<h4>La Procura di Castrovillari ha aperto un fascicolo d&#8217;indagine per accertare la conformit\u00e0 dei dispositivi di accertamento della velocit\u00e0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASTROVILLARI (CS) &#8211; Le pagine di Quicosenza in diverse occasioni hanno segnalato il particolare &#8216;caso&#8217; della presenza di autovelox lungo la<strong> statale 106 jonica<\/strong>, sospetti e raccolto decine di segnalazioni di utenti che avrebbero ricevuto numerose contravvenzioni per aver superato il limite di velocit\u00e0 di <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2910\" target=\"_blank\" rel=\"noopener\">un solo km\/h.<\/a> <\/span><\/strong>Oggi si apprende che la procura della Repubblica di Castrovillari ha aperto un&#8217;inchiesta sulla regolarit\u00e0 degli impianti autovelox installati nei territori di diversi Comuni dell&#8217;alto Jonio cosentino, lungo la strada statale 106.<\/p>\n<p>I comuni finiti nel mirino delle indagini sarebbero quelli di<strong> Cassano allo Ionio (Sibari), Villapiana, Trebisacce<\/strong>. I sospetti sono legati non solo alla modalit\u00e0 con la quale sono stati tarati ma anche legati alcuni comuni hanno personale della polizia municipale impiegato per diverso tempo in questa attivit\u00e0. Sembrerebbe dunque che quegli autovelox non siano stati installati con l&#8217;obiettivo di migliorare e garantire la sicurezza stradale, ma con ben altri scopi, ed in primo luogo quello di fare cassa. Le indagini sono partite dopo una serie di esposti arrivati in Procura e l&#8217;attivit\u00e0 di indagine \u00e8 partita subito dopo il periodo di Natale.<\/p>\n<p>&#8220;Temiamo che questi impianti siano stati montati non proprio per la sicurezza, ma piuttosto per <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/2901\" target=\"_blank\" rel=\"noopener\">fare cassa<\/a><\/strong><\/span>&#8221; dice il procuratore capo Eugenio Facciolla, interpellato al riguardo. &#8220;L&#8217;indagine &#8211; conferma il magistrato &#8211; \u00e8 in corso, stiamo verificando l&#8217;appropriatezza tecnica, la conformit\u00e0 e anche il posizionamento degli impianti e naturalmente anche tutto ci\u00f2 che porta, appunto, il denaro alle casse dei Comuni interessati&#8221;.<\/p>\n<h2>Leggi anche<\/h2>\n<p>https:\/\/quicosenza.it\/news\/2901<\/p>\n<p>https:\/\/quicosenza.it\/news\/provincia-cosenza\/182156-la-segnalazione-autovelox-truffa-a-trebisacce-serve-solo-per-incassare-non-per-la-sicurezza<\/p>\n<p>https:\/\/quicosenza.it\/news\/2910<\/p>\n<p>https:\/\/quicosenza.it\/news\/provincia-cosenza\/202640-i-furbetti-dellautovelox-sulla-106-in-provincia-di-cosenza-otto-indagati<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Procura di Castrovillari ha aperto un fascicolo d&#8217;indagine per accertare la conformit\u00e0 dei dispositivi di accertamento della velocit\u00e0<\/p>\n","protected":false},"author":42,"featured_media":105820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-105819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105820"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}