{"id":105826,"date":"2019-02-18T20:15:22","date_gmt":"2019-02-18T19:15:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/debiti-e-appalti-katya-gentile-si-scaglia-contro-occhiuto-e-il-sistema-cosenza\/"},"modified":"2023-01-16T18:23:01","modified_gmt":"2023-01-16T17:23:01","slug":"278435-debiti-e-appalti-katya-gentile-si-scaglia-contro-occhiuto-e-il-sistema-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278435-debiti-e-appalti-katya-gentile-si-scaglia-contro-occhiuto-e-il-sistema-cosenza\/","title":{"rendered":"Debiti e appalti: Katya Gentile si scaglia contro Occhiuto e il &#8216;sistema Cosenza&#8217;"},"content":{"rendered":"<h4>L&#8217;ex vice sindaco di Cosenza denuncia pubblicamente le contraddizioni dell&#8217;attuale amministrazione che a suo dire sta peggiorando la qualit\u00e0 della vita in citt\u00e0 ignorando le esigenze dei suoi abitanti<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00abLa polemica di questi giorni, &#8211; scrive in una nota Katya Gentile in veste di presidente dell\u2019associazione LegittimaMente &#8211; tra i consiglieri comunali del capoluogo di regione e l&#8217;onorevole Tallini, accusato di avere svenduto Catanzaro abdicando in favore di Occhiuto, per la candidatura a Governatore delle prossime elezioni regionali, mi ha dato lo spunto per una riflessione che vorrei condividere con l&#8217;amico Tallini e con tutti quelli che a Cosenza ci capitano una volta ogni tanto e pure di passaggio. Molti di quelli che parlano di un &#8220;ottimo amministratore&#8221; e non &#8220;osano&#8221; metterne in dubbio le capacit\u00e0, infatti, inseguono il mito dell&#8217;Amministrazione Occhiuto, che \u00e8 tanto vero quanto la leggenda del tesoro di Alarico. Si, perch\u00e9, il messaggio che viene esportato oltre il Campagnano, con una massiva campagna di disinformazione quotidiana, \u00e8: <strong>grazie a questo sindaco (ma che dico sindaco, profeta), che con la sua feconda produzione di &#8220;progetti&#8221; \u00e8 sempre un passo avanti agli altri e riesce a utilizzare tanti finanziamenti, Cosenza in questi anni \u00e8 cambiata<\/strong> ed i segni sono evidenti a tutti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Da piazza Bilotti a piazza Loreto, da piazza Riforma a San Domenico, da piazza XXV luglio a Santa Teresa fino alla nuova piazzetta di via Roma, la citt\u00e0 ha cambiato il suo volto, \u00e8 vero. Ma cos&#8217;\u00e8 davvero cambiato oltre la facciata e quali sono le conseguenze di questo cambiamento? <strong>Occhiuto, attraverso la sua fabbrica di progetti, ha impunemente sdoganato &#8220;il sistema Cosenza&#8221;, che, purtroppo, non risponde a principi di trasparenza, n\u00e9 di economicit\u00e0, n\u00e9 tanto meno di correttezza e legalit\u00e0.<\/strong> Questo sistema prevede, intanto, un esercito clientelare di dirigenti, ditte amiche e supporti al Rup, anche con incarichi stabili nei diversi settori del Comune, composto da collaboratori del suo studio, ex soci e colleghi creditori (architetti e imprenditori), che grava per la gran parte sulle casse comunali. Prevede che gli impegni e le liquidazioni, quando non c&#8217;\u00e8 capienza sui relativi capitoli di spesa, vengano iscritti su somme vincolate provenienti da mutui o finanziamenti dedicati, con una conseguente, puntuale, distrazione di fondi di bilancio. Prevede il metodo del frazionamento e del &#8220;sotto soglia&#8221; intrinseco al &#8220;sistema Cosenza&#8221; che \u00e8 diventato negli anni una vera e propria mangiatoia per i prescelti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Capita, poi, che la stessa ditta, in un breve lasso di tempo, per combinazione, riesca ad aggiudicarsi quattro grossi appalti<\/strong>, diversi, e che ci ritroviamo Cosenza tappezzata di &#8220;pietra lunare&#8221; e di granito cinese di scarsissima qualit\u00e0, tant&#8217;\u00e8 che alcuni tratti di piazza Fera-Bilotti, ad esempio, sono stati gi\u00e0 rifatti almeno tre o quattro volte in due anni, con dispendio di nuove ed ulteriori risorse economiche. Sempre lo stesso sistema prevedeva pure che i debiti personali del sindaco ricadessero sulle casse del Comune, attraverso un meccanismo contorto di inerzia, con la complicit\u00e0 di qualche dirigente. Paradossalmente, l&#8217;ente risulta non essersi mai costituito in pi\u00f9 di un giudizio, fino alla contumacia, ribaltando, cos\u00ec, i pignoramenti del primo cittadino sul nostro Comune. Peraltro, non \u00e8 dato sapere come sia andata a finire la storia, n\u00e8 se il giocattolo si sia rotto temporaneamente o a tempo indeterminato, dopo &#8220;lo sbianco&#8221;. Certamente lo scopriremo tra qualche tempo. Ma nell&#8217;immaginario collettivo, di chi vive oltre i confini cosentini, si \u00e8 instaurato anche un altro mito: Cosenza uguale a citt\u00e0 del benessere, del divertimento, della movida, delle grandiose e partecipate manifestazioni pubbliche a base di luci, canti e cotillons.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vede caro onorevole Tallini, ho il dovere di dirle, da ex amministratore e con cognizione di causa, che dietro a quest&#8217;immagine fintamente patinata, abilmente costruita in otto anni di bugie, mistificazioni, risultati truccati di farlocchi sondaggi commissionati, e con l&#8217;ausilio di una certa stampa servizievole e prezzolata, <strong>ci sono ancora troppi cosentini che hanno l&#8217;acqua in casa solo per tre ore al giorno, perch\u00e8 il problema non \u00e8 stato mai considerato e affrontato seriamente; abbiamo un centro storico abbandonato al degrado, fisico e sociale<\/strong>; abbiamo un teatro di tradizione declassato dal Ministero per la mancata programmazione della stagione lirica (in compenso assistiamo, al teatro Rendano, a spettacoli che di solito si tengono nei cinema); abbiamo una biblioteca civica i cui dipendenti non vengono pagati da anni ed il simbolo della cultura cosentina \u00e8 passato da Telesio ad Alarico e alle &#8220;buone feste cosentine&#8221; (per i circenses, sine pane, si continuano a sperperare tanti milioni di euro). E poco importa se, finanche nel salotto buono della citt\u00e0, si vedono circolare topi anche d&#8217;inverno, anche se un&#8217;opera di massiccia derattizzazione si era annunciata in agosto; se si \u00e8 perso il conto delle strade e dei marciapiedi dissestati; se la citt\u00e0 si allaga nei primi 10 minuti di pioggia; se all&#8217;improvviso si aprono voragini sulle strade; se, ancora nel 2019, ci sono cosentini che vivono in una macchina; se ci sono abitanti dei quartieri popolari e del centro storico abbandonati a se stessi, con l&#8217;eternit sui tetti ed i cumuli di spazzatura davanti la porta di casa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Poco importa se quello che lui chiama piano di mobilit\u00e0 dolce ha stravolto la viabilit\u00e0 cittadina, ha messo ulteriormente in crisi il commercio, mandato in tilt il traffico e aumentato esponenzialmente le immissioni di smog nelle uniche strade percorribili in auto.<strong> A chi interessa se ci sono tanti esercenti esasperati sull&#8217;orlo del fallimento, se ci sono innumerevoli cittadini che imprecano intrappolati su via Roma, su via Popilia o nei pressi dell&#8217;ingresso autostradale e se ci sono ambulanze bloccate nel traffico<\/strong> che tardano nei soccorsi, per effetto dei divieti e degli imbuti creati ad hoc da strade interdette, ztl e cambi di sensi di marcia, mai approvati in un PUT (piano urbano del traffico) obbligatorio per legge; persino il Piano di emergenza della Protezione Civile attualmente in vigore non \u00e8 applicabile. Nessuno s&#8217;\u00e8 accorto che ha dato il via ai lavori del &#8220;parco del benessere&#8221;, primo stralcio dei lavori della metro, senza che il progetto esecutivo dell&#8217;intera opera fosse stato approvato in Regione e senza che fosse stato inviato alla Commissione Europea.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quindi, stralcio di cosa? <strong>Il metodo utilizzato \u00e8 lo stesso usato per piazza Bilotti. Anche in quella circostanza, che fece scuola, si inizi\u00f2 dai lavori complementari, senza che il progetto esecutivo fosse stato approvato<\/strong>, per intascare l&#8217;anticipazione ed il primo SAL dalla Regione, rendicontando, peraltro, spese che di fatto sono inammissibili. Fatti che denunciai in Procura. Ahinoi, viviamo in una citt\u00e0 dove non importa a nessuno se una sentenza del TAR, che ordina la sospensione dei lavori di viale Mancini, viene disattesa per giorni. E sorge il dubbio che si sapesse gi\u00e0 che il Consiglio di Stato, solerte come non mai, si sarebbe espresso, addirittura, di domenica, per sospenderne gli effetti. Alle nostre latitudini, poi, caro Tallini, abbiamo anche la spinosa questione del nuovo ospedale. Non dimentichi che se si rischia di perdere i finanziamenti \u00e8 per responsabilit\u00e0 di quello stesso Sindaco che lei vedrebbe Governatore, della sua ostinata reticenza e del suo inattuabile progetto, che, proprio per com&#8217;\u00e8 stato pensato, prevede tra l&#8217;altro, un dispendio di svariati milioni di euro aggiuntivi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Mio caro onorevole, un buon amministratore, per essere definito tale, dovrebbe amministrare perseguendo principi di legalit\u00e0, trasparenza, economicit\u00e0, sussidiariet\u00e0 e ragionevolezza, esattamente il contrario di ci\u00f2 che accade da quando ad amministrare la citt\u00e0 di Cosenza c&#8217;\u00e8 Mario Occhiuto. A causa di un Consiglio comunale muto, sordo e cieco e di una truppa di yes man, all&#8217;uopo assoldata e preposta a divulgare &#8220;il verbo&#8221;, \u00e8 abituato ad essere l&#8217;uomo solo al comando, tranne quando c&#8217;\u00e8 da scaricare qualche responabilit\u00e0. Chiunque provi a muovere una critica politica o un parere di dissenso viene immediatamente etichettato nella categoria degli odiatori o dei complottisti. Con questa tecnica, sminuisce e azzera (nella sua mente) qualsiasi problematica, mortifica la libert\u00e0 di opinione e di parola di qualunque cittadino, singolo o associato, omette di dare risposte concrete ed appropriate e si veste da vittima. Approfitta di queste occasioni, infatti, per autoincensarsi e propagandare tutte le sue false virt\u00f9 che, a suo dire, sarebbero la causa che muoverebbe contro di lui gli attacchi degli invidiosi e dei bastian contrari per partito preso. Con questa mia, che ha il solo fine di fornire<strong> spunti ed elementi certi a quanti, come lei, risultano innamorati di una figura ideale che nella realt\u00e0 non esiste, invito tutti ad effettuare le dovute verifiche, su quanto da me sottoscritto, attraverso atti e documenti<\/strong>, prima di esporvi assumendovi addirittura la paternit\u00e0 della candidatura di Mario Occhiuto a Governatore della Regione Calabria, quale esempio di ottimo amministratore. Mi chiedo, infine, se in quel di Catanzaro sia mai giunta la notizia della depressione del nostro Sindaco, che ha depositato i certificati della patologia in in un&#8217;aula di tribunale. In Italia, di solito, ai depressi si ritira la patente, figuriamoci la guida di una citt\u00e0 o di un&#8217;intera regione. Il re \u00e8 nudo, caro on.le, e non vorrei che un giorno le si potesse imputare di essere stato uno stolto o di essere fatto della sua stessa pasta. Mi immedesimo ed io tra le due non saprei proprio scegliere. Certe posizioni potrebbero rivelarsi scomode e imbarazzanti, in un futuro, qui si spera ancora, molto vicino\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ex vice sindaco di Cosenza denuncia pubblicamente le contraddizioni dell&#8217;attuale amministrazione che a suo dire sta peggiorando la qualit\u00e0 della vita in citt\u00e0 ignorando le esigenze dei suoi abitanti<\/p>\n","protected":false},"author":43,"featured_media":105827,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-105826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105826"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105827"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}