{"id":105850,"date":"2019-02-19T11:51:18","date_gmt":"2019-02-19T10:51:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lavoratori-a-rischio-licenziamento-protestano-al-porto-di-gioia-tauro\/"},"modified":"2023-01-16T18:23:03","modified_gmt":"2023-01-16T17:23:03","slug":"278511-lavoratori-a-rischio-licenziamento-protestano-al-porto-di-gioia-tauro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278511-lavoratori-a-rischio-licenziamento-protestano-al-porto-di-gioia-tauro\/","title":{"rendered":"Lavoratori a rischio licenziamento protestano al porto di Gioia Tauro (FOTO)"},"content":{"rendered":"<h4>Portuali e sindaci chiedono di poter essere ascoltati dal ministro Toninelli che incontrer\u00e0 oggi a Roma le organizzazioni sindacali<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>GIOIA TAURO (RC) &#8211; Centinaia di portuali di Gioia Tauro e i sindaci della Piana si sono riuniti stamani davanti al gate portuale in attesa di notizie dal tavolo di confronto convocato al Ministero delle Infrastrutture sul futuro dello scalo. I sindaci hanno chiesto un incontro urgente con il ministro Toninelli ed hanno annunciato che non si muoveranno dalla loro protesta fin quando non arriver\u00e0 la convocazione, ritenendo di essere interlocutori istituzionali diretti del territorio sul quale sorge il porto. Posizione che hanno ribadito alle centinaia di portuali che stanno occupando simbolicamente l&#8217;ingresso dello scalo.<strong> In tarda mattinata il ministro Toninelli ed il suo staff incontreranno a Roma le organizzazioni sindacali e i rappresentanti delle societ\u00e0 Medcenter e Msc<\/strong> per cercare di affrontare i problemi che affliggono lo scalo. Tra i presenti al sit-in anche don Pino Demasi, referente di Libera della Piana, imprenditori, politici e mogli e figli del portuali che rischiano il licenziamento.<\/p>\n<p>&nbsp;<\/p>\n<h3>L&#8217;ESITO DELL&#8217;INCONTRO A ROMA CON IL MINISTRO<\/h3>\n<p><strong>Sospensione dei licenziamenti e investimenti pari a 120 milioni di euro per portare la capacit\u00e0 operativa del porto di Gioia Tauro a 4 milioni di Teus\u00a0<\/strong>(dagli attuali 2,4) l&#8217;unit\u00e0 di misura dei containers. Sono questi, secondo fonti sindacali, gli impegni assunti oggi da Mct, \u00a0che gestisce lo scalo calabrese, e Msc, che detiene il 50% della societ\u00e0, con il ministero delle Infrastrutture. L&#8217;azienda, secondo quanto si apprende dalle stesse fonti, non ha preso parte a Roma alla riunione indetta a Roma dal ministro Danilo Toninelli, ma ha fatto conoscere il suo orientamento. Il ministro ha quindi dato alla societ\u00e0 terminalista 60 giorni di tempo per attuare gli impegni, confermando quanto aveva gi\u00e0 minacciato in occasione della sua visita in Calabria: il ritiro della concessione in caso di inadempienza. Il sit-in dei\u00a0lavoratori \u00a0e delle loro famiglie, comunque, continua. A Gioia Tauro si attendono impegni pi\u00f9 precisi: &#8220;Mct \u00a0&#8211; spiega Domenico Lombardo, segretario territoriale dell&#8217;Uiltrasporti Porti &#8211; non ha fornito dettagli in merito alla volont\u00e0 di non procedere con i licenziamenti. E&#8217; chiaro che se veramente si portasse la capacit\u00e0 di Gioia Tauro a 4 milioni di teus, considerando che nel periodo di massima attivit\u00e0 raggiungemmo i 3,2 milioni, ci sarebbe lavoro per gli attuali e per altri occupati.\u00a0Continueremo &#8211; dice Lombardo &#8211; la protesta fino a quando non ne sapremo di pi\u00f9&#8221;.\u00a0 Mct, societ\u00e0 partecipata da\u00a0Contship\u00a0e\u00a0Msc, aveva annunciato nei giorni scorsi altri licenziamenti senza specificare il numero (circa 500 secondo stime sindacali) dopo i 377 gi\u00e0 attuati nel 2017 e annullati dalla magistratura su istanza degli interessati.<\/p>\n<p>&nbsp;<\/p>\n<h3>LA LETTERA DEL GOVERNATORE<\/h3>\n<p>&#8220;Si vuole segnalare con particolare urgenza la situazione drammatica determinatasi nel porto di Gioia Tauro, che si aggrava di giorno in giorno, a fronte di un mercato intercontinentale e mediterraneo che vede una forte ripresa sia di merci scambiate che di lavoro nei terminali portuali. La gravit\u00e0 della situazione viene tutta a scaricarsi sulle spalle dei lavoratori, delle loro famiglie e del territorio gi\u00e0 tanto provato&#8221;. \u00c9 quanto scrive il Governatore della Calabria, Mario Oliverio, attualmente ristretto a San Giovanni in Fiore con obbligo di dimora in una lettera inviata al Presidente del Consiglio, Giuseppe Conte, e, per conoscenza, al ministro dei Trasporti, Danilo Toninelli. &#8220;Il porto di Gioia Tauro &#8211; aggiunge Oliverio &#8211; per le sue caratteristiche, \u00e8 un porto nazionale, classificato nelle reti europee come porto &#8216;core&#8217; e pertanto la decisionalit\u00e0 ed i finanziamenti sono tutti a carico allo Stato. E ci\u00f2 vale a maggior ragione per i finanziamenti europei che arrivano allo Stato affinch\u00e9 li spenda attraverso i Pon nel porto di Gioia e nel suo retroporto. <strong>E quindi \u00e8 esplicitamente previsto che la Regione Calabria non possa spendere risorse Por nel porto di Gioia<\/strong>. La responsabilit\u00e0 sta quindi in capo al Governo centrale. Nel novembre 2018 abbiamo avuto modo di rappresentare per iscritto al Presidente del Consiglio, oltre che al Ministro delle Infrastrutture, ai Presidenti delle Camere ed a tutta la Deputazione calabrese, la grave situazione del porto di Gioia Tauro. Oggi la situazione \u00e8 ancora pi\u00f9 grave e potrebbe volgere all&#8217;irrimediabile, pur in un contesto marittimo internazionale positivo, qualora non si provveda con un immediato, deciso ed autorevole intervento del Governo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Portuali e sindaci chiedono di poter essere ascoltati dal ministro Toninelli che incontrer\u00e0 oggi a Roma le organizzazioni sindacali<\/p>\n","protected":false},"author":43,"featured_media":105851,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105850"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105851"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}