{"id":105946,"date":"2019-02-21T18:13:55","date_gmt":"2019-02-21T17:13:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tir-si-ribalta-sulla-statale-trasporta-materiale-plastico-foto-e-video\/"},"modified":"2023-01-16T18:23:08","modified_gmt":"2023-01-16T17:23:08","slug":"278857-tir-si-ribalta-sulla-statale-trasporta-materiale-plastico-foto-e-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278857-tir-si-ribalta-sulla-statale-trasporta-materiale-plastico-foto-e-video\/","title":{"rendered":"Tir si ribalta sulla statale, trasporta materiale plastico (Foto e video)"},"content":{"rendered":"<h4>Rimasto ferito in modo lieve l&#8217;autista soccorso dai sanitari del 118. All&#8217;opera i vigili del fuoco<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Tir si ribalta all&#8217;imbocco che collega la strada statale 280 con lo svincolo Localit\u00e0 Germaneto, direzione Lamezia Terme. L&#8217;autotreno trasporta rifiuti e materiali in plastica. Al momento sono in corso gli accertamenti per stabilire la causa che ha portato al ribaltamento.<br \/>\nIl conducente, unico passeggero a bordo del mezzo, ferito in modo lieve, \u00e8 stato soccorso dai sanitari del Suem 118 e trasferito presso la struttura ospedaliera per ulteriori controlli.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-278859 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/190d4833-0277-4c70-8a78-d51ba9ea1352-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p>Sul posto la squadra dei vigili del fuoco della sede Centrale \u00e8 intervenuta per la messa in sicurezza del mezzo, mentre la polizia stradale ha effettuato\u00a0 i rilievi, gli operatori Anas hanno controllato e deviato il traffico insieme alla polizia locale per quanto di competenza.\u00a0 Disagi per la viabilit\u00e0. I vigili del fuoco hanno richiesto l&#8217;intervento\u00a0dell&#8217;autogr\u00f9, proveniente dal comando provinciale di Vibo Valentia, per il recupero del mezzo. E&#8217; stato interrotto il transito nel tratto di strada sino al termine delle operazioni di recupero. subito dopo le operazioni di recupero dell&#8217;automezzo riposizionato su ruote il tratto di strada rimane ancora chiuso al transito per permettere agli operatori Anas di ripulire la sede stradale<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-278860 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/bc6c16c6-b3de-432e-81f0-73ab8131b878-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ff0000;\">VIDEO<\/span><\/h1>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"ribaltamento tir\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/Ga0RVAYc970?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rimasto ferito in modo lieve l&#8217;autista soccorso dai sanitari del 118. All&#8217;opera i vigili del fuoco<\/p>\n","protected":false},"author":44,"featured_media":105947,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105946"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105947"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}