{"id":105957,"date":"2019-02-22T08:45:11","date_gmt":"2019-02-22T07:45:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sedici-lavoratori-in-nero-nelle-mense-scolastiche\/"},"modified":"2023-01-16T18:23:10","modified_gmt":"2023-01-16T17:23:10","slug":"278875-sedici-lavoratori-in-nero-nelle-mense-scolastiche","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/278875-sedici-lavoratori-in-nero-nelle-mense-scolastiche\/","title":{"rendered":"Sedici lavoratori in nero nelle mense scolastiche"},"content":{"rendered":"<h4>A scoprire i lavoratori senza alcun contratto i carabinieri e i colleghi del Comando Tutela Lavoro del Gruppo di Napoli e Nuclei Ispettorato del Lavoro di Crotone, Cosenza e Catanzaro.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PETILIA POLICASTRO (KR) &#8211; Hanno controllato le ditte affidatarie del servizio mensa di diversi istituti i carabinieri ed hanno scoperto ben 16 lavoratori in nero; in pratica i pasti che andavano sulle tavole dei ragazzi delle scuole venivano preparati in due diverse aziende, da personale che non aveva tutela legale e non era contrattualizzata. Le ispezioni hanno riguardato le sedi principali ma anche sette istituti scolastici locali. Nei confronti delle ditte affidatarie degli appalti sono state elevate sanzioni amministrative che superano i 177 mila euro; la cosiddetta maxisanzione che prevede multe a scaglioni a seconda del numero di giornate lavorative prestate. Recuperati inoltre contributi previdenziali per 10 mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A scoprire i lavoratori senza alcun contratto i carabinieri e i colleghi del Comando Tutela Lavoro del Gruppo di Napoli e Nuclei Ispettorato del Lavoro di Crotone, Cosenza e Catanzaro.<\/p>\n","protected":false},"author":42,"featured_media":105958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-105957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=105957"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/105957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/105958"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=105957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=105957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=105957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}