{"id":106046,"date":"2019-02-23T19:17:12","date_gmt":"2019-02-23T18:17:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arrestato-per-furto-evade-per-rubare-ancora-finisce-in-carcere\/"},"modified":"2023-01-16T18:23:16","modified_gmt":"2023-01-16T17:23:16","slug":"279143-arrestato-per-furto-evade-per-rubare-ancora-finisce-in-carcere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/279143-arrestato-per-furto-evade-per-rubare-ancora-finisce-in-carcere\/","title":{"rendered":"Arrestato per furto evade per rubare ancora: finisce in carcere"},"content":{"rendered":"<h4>Spina, 29 anni viene sorpreso in flagranza di reato mentre tenta di rubare del materiale edile. Finisce agli arresti domiciliari. Ribeccato dall&#8217;Arma con le mani nel sacco in meno di 24 ore<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Nella tarda mattinata di ieri le sirene della radiomobile dell&#8217;Arma riecheggiavano in citt\u00e0. I militari dell&#8217;Arma dell&#8217;Aliquota Radiomobile diretta dal maresciallo Italiano, unitamente ai colleghi della stazione di Cosenza Principale diretta dal luogotenente Morrone, della Compagnia di Cosenza al comando del capitano Merola avevano braccato un ragazzo noto alle forze dell&#8217;ordine F.S. , difeso dall&#8217;avvocato Cristian Cristiano, mentre aveva tentato di rubare all&#8217;interno di un furgone Iveco parcheggiato in via Piave. Il mezzo conteneva attrezzatura e materiale edile. Il ventottenne aveva gi\u00e0 infranto il parabrezza e cercava di impossessarsi del bottino. Il proprietario del furgone, un operaio della ditta edile, avvistato il ladro \u00e8 riuscito a bloccarlo e chiamare i carabinieri. Ancora una volta il coraggio di un cittadino onesto e la rapidit\u00e0 d\u2019intervento dei Carabinieri hanno garantito il migliore risultato.<\/p>\n<p>Il ventottenne\u00a0 tratto in arresto per tentato furto \u00e8 stato tradotto dai militari della stazione Principale, presso la sua abitazione su disposizione della Procura della Repubblica di Cosenza in attesa della direttissima che si sarebbe dovuta celebrare nella mattinata di oggi. Ma, intorno alle otto del mattino, il giovane \u00e8 stato bloccato dai militari dell&#8217;Aliquota radiomobile. All&#8217;occhio vigile dei carabinieri, durante un controllo del territorio non \u00e8 sfuggito il giovane che si allontanava a passo svelto.<\/p>\n<p>Il ragazzo \u00e8 stato avvistato tra piazza Giacomo Mancini, meglio conosciuta come &#8220;I due Fiumi&#8221;, e via XXIV Maggio. Aveva in mano delle cassette per attrezzi edili. Alla vista dei carabinieri ha cercaro di disfarsi del bottino. Incurante delle restrizioni impostegli in attesa del rito direttissimo, evadendo dagli arresti domiciliari, \u00e8 tornato dunque in pieno centro, questa volta su viale Trieste per rubare all&#8217;interno dell&#8217;ennesimo furgoncino materiale edile, mentre gli operai stavano effettuando lavori presso il Banco di Napoli.<\/p>\n<p>I Militari quindi, avendolo intercettato mentre cercava di fuggire e riconoscendolo, riuscivano ad immobilizzarlo ed a trarlo nuovamente in arresto per il medesimo reato del giorno precedente. Lo stesso, a questo punto, \u00e8 stato condotto direttamente presso il Tribunale di Cosenza dove era in programma l\u2019udienza di convalida per i fatti accaduti precedentemente. Il Giudice, su richiesta del Pubblico Ministero Cozzolino, alla luce anche degli eventi appena successi, nel convalidare gli arresti, ha disposto l\u2019immediata traduzione dell\u2019arrestato, presso la Casa Circondariale di Cosenza \u201cSergio Cosmai\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spina, 29 anni viene sorpreso in flagranza di reato mentre tenta di rubare del materiale edile. Finisce agli arresti domiciliari. Ribeccato dall&#8217;Arma con le mani nel sacco in meno di 24 ore<\/p>\n","protected":false},"author":40,"featured_media":106047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-106046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106046"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106047"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}