{"id":106143,"date":"2019-02-26T10:48:51","date_gmt":"2019-02-26T09:48:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrolibero-teneva-la-moglie-segregata-in-casa-arrestato\/"},"modified":"2023-01-16T18:23:21","modified_gmt":"2023-01-16T17:23:21","slug":"279554-castrolibero-teneva-la-moglie-segregata-in-casa-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/279554-castrolibero-teneva-la-moglie-segregata-in-casa-arrestato\/","title":{"rendered":"Castrolibero, teneva la moglie segregata in casa. Arrestato"},"content":{"rendered":"<h4>Da tre giorni l&#8217;aveva chiusa dentro casa, segregata da sabato scorso; la donna spaventata ha allertato i carabinieri e chiesto il loro aiuto<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS) &#8211; L&#8217;hanno liberata ieri mattina i carabinieri della Compagnia di Cosenza e contestualmente hanno arrestato per sequestro di persona <strong>M.A., 41enne cosentino<\/strong>, gi\u00e0 stato sottoposto alla misura cautelare all\u2019obbligo di firma.<\/p>\n<h4>I fatti<\/h4>\n<p>Ieri mattina, il 112 della Centrale Operativa di Cosenza riceve una telefonata. Dall&#8217;altra parte una donna, spaventata, che ha rivelato ai militari di essere stata rinchiusa dal coniuge nella propria abitazione in via F. Coppi a Castrolibero. I militari della\u00a0locale stazione si sono subito precipitati nell\u2019abitazione trovando per\u00f2, l\u2019ingresso chiuso da un <strong>portone blindato<\/strong> e impossibilitati ad accedere, ma <strong>sentendo le grida della malcapitata<\/strong>, sono riusciti a rintracciare in pochi minuti il marito. L&#8217;uomo era in possesso<strong> dell\u2019unico mazzo di chiavi della porta<\/strong>. Cos\u00ec sono riusciti ad aprire e una\u00a0volta entrati si sono accorti che la signora era in un <strong>angolo della mansarda<\/strong>\u00a0(al terzo piano dell\u2019abitazione), visibilmente <strong>terrorizzata<\/strong>. Cercava protezione dietro i militari, per poi tranquillizzarsi raccontando i fatti accaduti. La stessa \u00e8 stata poi accompagnata presso la Stazione di Castrolibero dove ha spiegato come il marito l\u2019avesse <strong>segregata all\u2019improvviso dalla serata di sabato<\/strong>, per motivi legati alla sua ossessiva <strong>gelosia<\/strong>. Ma la donna avrebbe subito maltrattamenti anche in passato.<\/p>\n<p>Nel frattempo, terminati gli accertamenti di rito, il 41enne \u00e8 stato arrestato e tradotto presso un\u2019abitazione diversa da quella della moglie, ovvero dai suoi genitori, in regime di arresti domiciliari su disposizione della Procura della Repubblica di Cosenza. La povera donna, \u00e8 cos\u00ec riuscita a riappropriarsi della sua libert\u00e0, lontana dal suo aguzzino, l&#8217;uomo che aveva sposato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da tre giorni l&#8217;aveva chiusa dentro casa, segregata da sabato scorso; la donna spaventata ha allertato i carabinieri e chiesto il loro aiuto<\/p>\n","protected":false},"author":42,"featured_media":106144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[564],"tags":[],"class_list":["post-106143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106143"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106144"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}